{"id":11982,"date":"2026-05-17T17:51:35","date_gmt":"2026-05-17T23:51:35","guid":{"rendered":"https:\/\/mccormickmurphy.com\/?page_id=11982"},"modified":"2026-06-22T09:50:12","modified_gmt":"2026-06-22T15:50:12","slug":"auto-accident-lawyer-englewood","status":"publish","type":"page","link":"https:\/\/mccormickmurphy.com\/es\/auto-accident-lawyer-englewood\/","title":{"rendered":"Abogado de accidentes automovil\u00edsticos en Englewood"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"11982\" class=\"elementor elementor-11982\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eb8eac6 elementor-section-content-middle elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eb8eac6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5998f8d1\" data-id=\"5998f8d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d2c067c elementor-icon-list--layout-inline elementor-mobile-align-center elementor-tablet-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5d2c067c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/mccormickmurphy.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/kojCLybzxiurNg5JA\" title=\"Abogados de lesiones personales en Colorado Springs\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Colorado Springs<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/eirbTTn8gtvYxwm98\" title=\"Abogados de lesiones personales en Pueblo\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pueblo<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/y9gVVznr14hyoWwr9\" title=\"Abogados de lesiones personales en Denver\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Denver<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-56e4805c elementor-hidden-phone elementor-hidden-tablet\" data-id=\"56e4805c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29771d7c elementor-widget elementor-widget-heading\" data-id=\"29771d7c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><p class=\"e-add-hoverheading elementor-heading-title elementor-size-default\"><a href=\"tel:%20(888)-668-1182\">Llama al (888)-668-1182<\/a><\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bd0d5d9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bd0d5d9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3c30dc41\" data-id=\"3c30dc41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd93757 elementor-widget elementor-widget-image\" data-id=\"cd93757\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/es\/\" title=\"Abogados de lesiones personales en Colorado\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"261\" height=\"80\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png\" class=\"attachment-full size-full wp-image-136\" alt=\"Personal Injury Lawyers Colorado\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7cd49a88\" data-id=\"7cd49a88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fe93ca3 elementor-nav-menu__align-end elementor-nav-menu--stretch elementor-nav-menu--dropdown-mobile elementor-nav-menu__text-align-center elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"6fe93ca3\" data-element_type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/mccormickmurphy.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-nav-menu.min.css\">\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-text e--animation-sink\">\n\t\t\t\t<ul id=\"menu-1-6fe93ca3\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1028\"><a href=\"\/es\/\" title=\"Abogados de lesiones personales | Colorado\" class=\"elementor-item\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/11\/small-white-house-icon.png\"  \/><\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-131\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/\" title=\"Acerca de nuestros abogados especializados en lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-item\">Acerca de<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-198\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/kirk-mccormick\/\" title=\"Kirk McCormick | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\">Kirk McCormick<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-202\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/james-murphy\/\" title=\"James Murphy | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\">James Murphy<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-206\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/sample-case-result\/\" title=\"Resultado de un caso de muestra | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\">Resultado de un caso de muestra<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-209\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/m-m-in-the-community\/\" title=\"En la comunidad | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">M + M en la comunidad<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-220\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/testimonials\/\" title=\"Testimonios | Abogados de lesiones personales | Colorado\" class=\"elementor-sub-item\">Testimonios<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-134\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/\" title=\"\u00c1reas de pr\u00e1ctica | Abogados de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\">\u00c1reas de pr\u00e1ctica<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-219\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/\" title=\"Abogado de accidentes de tr\u00e1fico | Abogado de accidentes de tr\u00e1fico | Colorado Springs\" class=\"elementor-sub-item\">Accidentes de tr\u00e1fico<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-236\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-distracted-driving-accident-lawyer\/\" title=\"Abogado de conducci\u00f3n distra\u00edda en Colorado Springs\" class=\"elementor-sub-item\">Conducci\u00f3n distra\u00edda<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-244\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-drunk-driving-accident-lawyers\/\" title=\"Abogado de accidentes por conducir ebrio en Colorado Springs\" class=\"elementor-sub-item\">Conductor ebrio<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-252\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-failure-to-yield-right-of-way-accident-lawyers\/\" title=\"Abogado de accidentes por no ceder el paso en Colorado Springs\" class=\"elementor-sub-item\">No ceder<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-263\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-head-on-truck-and-car-accident-lawyers\/\" title=\"Abogado de accidentes de tr\u00e1fico de frente en Colorado Springs\" class=\"elementor-sub-item\">Accidentes frontales<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-285\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-hit-and-run-accident-lawyers\/\" title=\"Abogado de accidentes de choque y fuga en Colorado Springs\" class=\"elementor-sub-item\">Choque y fuga<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-294\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-intersection-accident-lawyers\/\" title=\"Abogados de accidentes en intersecciones en Colorado Springs\" class=\"elementor-sub-item\">Accidentes en intersecciones<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-297\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-multi-vehicle-accident-pileups-lawyers\/\" title=\"Abogado de accidentes automovil\u00edsticos m\u00faltiples en Colorado Springs\" class=\"elementor-sub-item\">Accidentes de varios veh\u00edculos<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-306\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-reckless-driving-accident-lawyers\/\" title=\"Abogado de accidentes por conducci\u00f3n imprudente en Colorado Springs\" class=\"elementor-sub-item\">Accidentes por conducci\u00f3n imprudente<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-362\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-scooter-accident-lawyers\/\" title=\"Abogado de accidentes de patinetes el\u00e9ctricos en Colorado Springs\" class=\"elementor-sub-item\">Accidentes de scooter<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-319\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/motorcycle-accidents\/\" title=\"Abogados de accidentes de motocicleta en Colorado Springs\" class=\"elementor-sub-item\">Accidentes de motocicleta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-326\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/wrongful-death\/\" title=\"Abogado de muerte por negligencia en Colorado Springs\" class=\"elementor-sub-item\">Muerte por negligencia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-329\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/slip-fall-accidents\/\" title=\"Abogado de resbalones y ca\u00eddas en Colorado Springs\" class=\"elementor-sub-item\">Accidentes por resbalones y ca\u00eddas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-332\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/insurance-bad-faith\/\" title=\"Abogado de mala fe en seguros en Colorado Springs\" class=\"elementor-sub-item\">Mala fe en seguros<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-338\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/dog-bite\/\" title=\"Abogado de lesiones por mordedura de perro en Colorado Springs\" class=\"elementor-sub-item\">Mordedura de perro<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-347\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/traumatic-brain-injuries\/\" title=\"Abogado de lesiones cerebrales traum\u00e1ticas en Colorado Springs\" class=\"elementor-sub-item\">Lesiones cerebrales traum\u00e1ticas<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-132\"><a href=\"https:\/\/mccormickmurphy.com\/es\/areas-we-serve\/\" title=\"\u00c1reas en las que prestamos servicios | Abogados de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\">Ubicaciones<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-381\"><a href=\"https:\/\/mccormickmurphy.com\/es\/\" title=\"Abogados de lesiones personales | Colorado Springs\" class=\"elementor-sub-item\">Colorado Springs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-380\"><a href=\"https:\/\/mccormickmurphy.com\/es\/denver-personal-injury-attorneys\/\" title=\"Abogados de lesiones personales | Denver\" class=\"elementor-sub-item\">Denver<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-373\"><a href=\"https:\/\/mccormickmurphy.com\/es\/pueblo-personal-injury-attorneys\/\" title=\"Abogados de lesiones personales | Pueblo\" class=\"elementor-sub-item\">Pueblo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-397\"><a title=\"Recursos | McCormick &amp; Murphy, PC\" class=\"elementor-item\">Recursos<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-440\"><a href=\"https:\/\/mccormickmurphy.com\/es\/accident-reports\/\" title=\"Informes de accidentes policiales | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Obtenga su informe de accidente<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-558\"><a href=\"https:\/\/mccormickmurphy.com\/es\/hire-attorney\/\" title=\"Preguntas frecuentes sobre la contrataci\u00f3n de un abogado | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Preguntas frecuentes sobre la contrataci\u00f3n de un abogado<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-634\"><a href=\"https:\/\/mccormickmurphy.com\/es\/bad-faith-faqs\/\" title=\"Preguntas que debe hacerle a un abogado especializado en lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Preguntas frecuentes sobre lesiones personales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-562\"><a href=\"https:\/\/mccormickmurphy.com\/es\/auto-settlement\/\" title=\"Maximice la liquidaci\u00f3n de su seguro de autom\u00f3vil | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Preguntas frecuentes sobre accidentes automovil\u00edsticos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-637\"><a href=\"https:\/\/mccormickmurphy.com\/es\/video-center\/\" title=\"Centro de video | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Centro de video<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-396\"><a href=\"https:\/\/mccormickmurphy.com\/es\/blog\/\" title=\"Blog | Abogados de lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-item\">Blog<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-102\"><a href=\"https:\/\/mccormickmurphy.com\/es\/contact-us\/\" title=\"Cont\u00e1ctenos | Abogado de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\">Contacto<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-7358\"><a href=\"https:\/\/clients.clio.com\/login\" class=\"elementor-item\">Portal del cliente<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-7309\"><a href=\"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11982\" class=\"elementor-item elementor-item-anchor\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_US.png\" width=\"18\" height=\"12\" alt=\"en_US\" title=\"English\"><span class=\"trp-ls-language-name\">English<\/span><\/span><\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Alternar men\u00fa\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Men\u00fa<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-6fe93ca3\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1028\"><a href=\"\/es\/\" title=\"Abogados de lesiones personales | Colorado\" class=\"elementor-item\" tabindex=\"-1\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/11\/small-white-house-icon.png\"  \/><\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-131\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/\" title=\"Acerca de nuestros abogados especializados en lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-item\" tabindex=\"-1\">Acerca de<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-198\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/kirk-mccormick\/\" title=\"Kirk McCormick | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\" tabindex=\"-1\">Kirk McCormick<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-202\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/james-murphy\/\" title=\"James Murphy | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\" tabindex=\"-1\">James Murphy<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-206\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/sample-case-result\/\" title=\"Resultado de un caso de muestra | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\" tabindex=\"-1\">Resultado de un caso de muestra<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-209\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/m-m-in-the-community\/\" title=\"En la comunidad | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">M + M en la comunidad<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-220\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/testimonials\/\" title=\"Testimonios | Abogados de lesiones personales | Colorado\" class=\"elementor-sub-item\" tabindex=\"-1\">Testimonios<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-134\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/\" title=\"\u00c1reas de pr\u00e1ctica | Abogados de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\" tabindex=\"-1\">\u00c1reas de pr\u00e1ctica<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-219\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/\" title=\"Abogado de accidentes de tr\u00e1fico | Abogado de accidentes de tr\u00e1fico | Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes de tr\u00e1fico<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-236\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-distracted-driving-accident-lawyer\/\" title=\"Abogado de conducci\u00f3n distra\u00edda en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Conducci\u00f3n distra\u00edda<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-244\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-drunk-driving-accident-lawyers\/\" title=\"Abogado de accidentes por conducir ebrio en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Conductor ebrio<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-252\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-failure-to-yield-right-of-way-accident-lawyers\/\" title=\"Abogado de accidentes por no ceder el paso en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">No ceder<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-263\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-head-on-truck-and-car-accident-lawyers\/\" title=\"Abogado de accidentes de tr\u00e1fico de frente en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes frontales<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-285\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-hit-and-run-accident-lawyers\/\" title=\"Abogado de accidentes de choque y fuga en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Choque y fuga<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-294\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-intersection-accident-lawyers\/\" title=\"Abogados de accidentes en intersecciones en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes en intersecciones<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-297\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-multi-vehicle-accident-pileups-lawyers\/\" title=\"Abogado de accidentes automovil\u00edsticos m\u00faltiples en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes de varios veh\u00edculos<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-306\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-reckless-driving-accident-lawyers\/\" title=\"Abogado de accidentes por conducci\u00f3n imprudente en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes por conducci\u00f3n imprudente<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-362\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-scooter-accident-lawyers\/\" title=\"Abogado de accidentes de patinetes el\u00e9ctricos en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes de scooter<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-319\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/motorcycle-accidents\/\" title=\"Abogados de accidentes de motocicleta en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes de motocicleta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-326\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/wrongful-death\/\" title=\"Abogado de muerte por negligencia en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Muerte por negligencia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-329\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/slip-fall-accidents\/\" title=\"Abogado de resbalones y ca\u00eddas en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes por resbalones y ca\u00eddas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-332\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/insurance-bad-faith\/\" title=\"Abogado de mala fe en seguros en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Mala fe en seguros<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-338\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/dog-bite\/\" title=\"Abogado de lesiones por mordedura de perro en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Mordedura de perro<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-347\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/traumatic-brain-injuries\/\" title=\"Abogado de lesiones cerebrales traum\u00e1ticas en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Lesiones cerebrales traum\u00e1ticas<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-132\"><a href=\"https:\/\/mccormickmurphy.com\/es\/areas-we-serve\/\" title=\"\u00c1reas en las que prestamos servicios | Abogados de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\" tabindex=\"-1\">Ubicaciones<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-381\"><a href=\"https:\/\/mccormickmurphy.com\/es\/\" title=\"Abogados de lesiones personales | Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Colorado Springs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-380\"><a href=\"https:\/\/mccormickmurphy.com\/es\/denver-personal-injury-attorneys\/\" title=\"Abogados de lesiones personales | Denver\" class=\"elementor-sub-item\" tabindex=\"-1\">Denver<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-373\"><a href=\"https:\/\/mccormickmurphy.com\/es\/pueblo-personal-injury-attorneys\/\" title=\"Abogados de lesiones personales | Pueblo\" class=\"elementor-sub-item\" tabindex=\"-1\">Pueblo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-397\"><a title=\"Recursos | McCormick &amp; Murphy, PC\" class=\"elementor-item\" tabindex=\"-1\">Recursos<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-440\"><a href=\"https:\/\/mccormickmurphy.com\/es\/accident-reports\/\" title=\"Informes de accidentes policiales | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Obtenga su informe de accidente<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-558\"><a href=\"https:\/\/mccormickmurphy.com\/es\/hire-attorney\/\" title=\"Preguntas frecuentes sobre la contrataci\u00f3n de un abogado | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Preguntas frecuentes sobre la contrataci\u00f3n de un abogado<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-634\"><a href=\"https:\/\/mccormickmurphy.com\/es\/bad-faith-faqs\/\" title=\"Preguntas que debe hacerle a un abogado especializado en lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Preguntas frecuentes sobre lesiones personales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-562\"><a href=\"https:\/\/mccormickmurphy.com\/es\/auto-settlement\/\" title=\"Maximice la liquidaci\u00f3n de su seguro de autom\u00f3vil | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Preguntas frecuentes sobre accidentes automovil\u00edsticos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-637\"><a href=\"https:\/\/mccormickmurphy.com\/es\/video-center\/\" title=\"Centro de video | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Centro de video<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-396\"><a href=\"https:\/\/mccormickmurphy.com\/es\/blog\/\" title=\"Blog | Abogados de lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-item\" tabindex=\"-1\">Blog<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-102\"><a href=\"https:\/\/mccormickmurphy.com\/es\/contact-us\/\" title=\"Cont\u00e1ctenos | Abogado de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\" tabindex=\"-1\">Contacto<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-7358\"><a href=\"https:\/\/clients.clio.com\/login\" class=\"elementor-item\" tabindex=\"-1\">Portal del cliente<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-7309\"><a href=\"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11982\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_US.png\" width=\"18\" height=\"12\" alt=\"en_US\" title=\"English\"><span class=\"trp-ls-language-name\">English<\/span><\/span><\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5863c24b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5863c24b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-e-bg-lazyload=\"\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73ee97df\" data-id=\"73ee97df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49df690b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49df690b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f0cf89a\" data-id=\"1f0cf89a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ebd8e2a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"6ebd8e2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Abogado de accidentes automovil\u00edsticos en Englewood<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69114856 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"69114856\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1dc00b1c\" data-id=\"1dc00b1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3aec6d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3aec6d7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ddacf6\" data-id=\"0ddacf6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46f49b2 elementor-widget elementor-widget-text-editor\" data-id=\"46f49b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>El perito de seguros te llama incluso antes de que llegues a casa del hospital. Suena amable. Dice que solo quiere ayudarte. Te pregunta si puedes dar una breve declaraci\u00f3n grabada, solo para agilizar el proceso.<\/p><p>Esto no es ayuda. Esto es estrategia.<\/p><p>El perito trabaja para una empresa cuyo modelo de negocio se basa en pagarle lo menos posible. Cada pregunta que le hacen est\u00e1 dise\u00f1ada para limitar su indemnizaci\u00f3n. Cada retraso que provocan est\u00e1 calculado para presionarlo a llegar a un acuerdo antes de que comprenda el verdadero valor de su caso.<\/p><p>Si usted ha resultado herido en un <a href=\"\/es\/denver-car-accident-lawyer\/\">accidente de coche<\/a> En Englewood, las primeras 72 horas marcan el rumbo de todo lo que sucede despu\u00e9s. Las decisiones que tome ahora mismo \u2014con qui\u00e9n hable, qu\u00e9 diga, qu\u00e9 firme\u2014 determinar\u00e1n si recibe una indemnizaci\u00f3n completa o si se conforma con una fracci\u00f3n del valor de su caso.<\/p><p><a href=\"https:\/\/mccormickmurphy.com\/es\/denver-personal-injury-attorneys\/\">McCormick y Murphy, PC<\/a>\u00a0Representamos a personas de toda el \u00e1rea metropolitana de Denver que han resultado heridas en accidentes automovil\u00edsticos. Hemos visto todas las t\u00e1cticas que usan las compa\u00f1\u00edas de seguros y sabemos exactamente c\u00f3mo contrarrestarlas. Llame.\u00a0<a href=\"tel:888-668-1182\">888-668-1182<\/a>\u00a0Hablar con un abogado que proteger\u00e1 tus derechos desde el primer d\u00eda.<\/p><h2><strong>\u00bfQu\u00e9 sucede en las primeras 72 horas despu\u00e9s de un accidente?<\/strong><\/h2><p>Los momentos posteriores a una colisi\u00f3n son ca\u00f3ticos. Se comprueba si hay heridos. Se intercambia informaci\u00f3n. Se intenta asimilar lo que acaba de ocurrir.<\/p><p>Mientras usted hace eso, la compa\u00f1\u00eda de seguros ya est\u00e1 preparando su defensa.<\/p><p>Los peritos saben que la mayor\u00eda de las personas no comprenden sus derechos inmediatamente despu\u00e9s de un accidente. Saben que usted est\u00e1 abrumado. Saben que siente dolor. Saben que nunca antes ha tenido que lidiar con una reclamaci\u00f3n por lesiones personales. Y utilizan todo eso a su favor.<\/p><p>La primera llamada suele llegar en cuesti\u00f3n de horas. El perito se mostrar\u00e1 comprensivo. Le dir\u00e1 que quiere resolver esto r\u00e1pidamente para que pueda concentrarse en su recuperaci\u00f3n. Le pedir\u00e1 que describa lo sucedido, con sus propias palabras, sin formalidades.<\/p><p>Esa conversaci\u00f3n \u201cinformal\u201d est\u00e1 siendo grabada. Cada palabra que diga ser\u00e1 analizada en busca de cualquier elemento que pueda usarse para reducir o denegar su reclamaci\u00f3n. Si dice que siente el cuello \u201cbien\u201d por cortes\u00eda, esa declaraci\u00f3n se utilizar\u00e1 para argumentar que sus lesiones no son graves. Si no recuerda todos los detalles porque a\u00fan est\u00e1 en estado de shock, eso se interpretar\u00e1 como una inconsistencia.<\/p><p>No est\u00e1 obligado a prestar declaraci\u00f3n grabada ante la compa\u00f1\u00eda de seguros del otro conductor. No est\u00e1 obligado a proporcionar autorizaciones m\u00e9dicas. No est\u00e1 obligado a llegar a un acuerdo r\u00e1pidamente solo porque le est\u00e9n presionando.<\/p><p>Lo que usted debe hacer es proteger sus derechos legales. Esto significa consultar con un abogado antes de hablar con cualquier compa\u00f1\u00eda de seguros, incluida la suya.<\/p><h2><strong>Por qu\u00e9 su propia compa\u00f1\u00eda de seguros no siempre est\u00e1 de su lado<\/strong><\/h2><p>La gente da por sentado que su propia compa\u00f1\u00eda de seguros les ayudar\u00e1. Llevas a\u00f1os pagando las primas. Has sido un buen cliente. Cuando los necesites, estar\u00e1n ah\u00ed.<\/p><p>Esa suposici\u00f3n le cuesta a la gente miles de d\u00f3lares cada d\u00eda.<\/p><p>Tu compa\u00f1\u00eda de seguros no te representa. Es una empresa. Y como toda empresa, su objetivo es maximizar sus ganancias. Cada d\u00f3lar que te pagan es un d\u00f3lar que no va a parar a sus accionistas.<\/p><p>Si tienes cobertura para conductores sin seguro o con seguro insuficiente (que es precisamente lo que necesitas cuando el otro conductor no tiene seguro o no tiene suficiente), ahora est\u00e1s presentando una reclamaci\u00f3n contra tu propia p\u00f3liza. Tu compa\u00f1\u00eda de seguros se convierte en la parte contraria. Investigar\u00e1n tu reclamaci\u00f3n del mismo modo que lo har\u00eda la aseguradora del otro conductor. Buscar\u00e1n motivos para denegar o reducir tu indemnizaci\u00f3n.<\/p><p>Incluso cuando no presentas una reclamaci\u00f3n por cobertura de automovilista sin seguro o con seguro insuficiente, tu propia aseguradora puede crearte problemas. Podr\u00edan argumentar que tu p\u00f3liza no cubre ciertos da\u00f1os. Podr\u00edan retrasar el procesamiento de tu cobertura de gastos m\u00e9dicos. Podr\u00edan presionarte para que llegues a un acuerdo con la aseguradora del conductor culpable por una cantidad menor a la que te corresponde, para as\u00ed evitar tener que pagar tu cobertura por automovilista sin seguro.<\/p><p>Esto no es especulaci\u00f3n. Esto es lo que vemos caso tras caso en Denver, Lakewood, Arvada y Englewood.<\/p><h2><strong>C\u00f3mo se determina la culpa y por qu\u00e9 es importante<\/strong><\/h2><p>Colorado aplica una regla de negligencia comparativa modificada. Esto significa que puede recibir una indemnizaci\u00f3n incluso si tuvo parte de la culpa del accidente, siempre y cuando su responsabilidad sea inferior al 50 por ciento.<\/p><p>Si usted tuvo un 20 por ciento de culpa, su indemnizaci\u00f3n se reduce en un 20 por ciento. Si tuvo un 49 por ciento de culpa, a\u00fan recibir\u00e1 una indemnizaci\u00f3n, aunque reducida en un 49 por ciento. Pero si se determina que usted tuvo un 50 por ciento o m\u00e1s de culpa, no recibir\u00e1 ninguna indemnizaci\u00f3n.<\/p><p>Las compa\u00f1\u00edas de seguros lo saben. Y lo utilizan.<\/p><p>Incluso cuando el conductor del otro veh\u00edculo haya sido claramente responsable del accidente, los peritos intentar\u00e1n culparte a ti. Alegar\u00e1n que ibas a exceso de velocidad. Dir\u00e1n que podr\u00edas haber frenado antes. Argumentar\u00e1n que estabas distra\u00eddo o que no reaccionaste a tiempo para evitar el accidente.<\/p><p>El objetivo es aumentar tu porcentaje de culpa lo suficiente como para que o bien no recuperes nada o tu indemnizaci\u00f3n se reduzca tan dr\u00e1sticamente que te rindas y aceptes un acuerdo bajo.<\/p><p>Para defenderse se necesitan pruebas. Informes policiales. Declaraciones de testigos. An\u00e1lisis de reconstrucci\u00f3n del accidente. Historiales m\u00e9dicos que documenten la gravedad y la causa de sus lesiones. Fotograf\u00edas del lugar del accidente. Datos de los registradores de eventos de los veh\u00edculos.<\/p><p>La compa\u00f1\u00eda de seguros tiene investigadores y abogados trabajando para reconstruir su versi\u00f3n de los hechos. Usted necesita que alguien haga lo mismo por usted. Esperar semanas para contratar a un abogado significa esperar semanas para reunir pruebas; y durante ese tiempo, los testigos olvidan detalles, las pruebas f\u00edsicas desaparecen y las grabaciones de vigilancia se borran.<\/p><h2><strong>Qu\u00e9 puedes recuperar realmente despu\u00e9s de un accidente de coche<\/strong><\/h2><p>La mayor\u00eda de la gente piensa que una reclamaci\u00f3n por lesiones personales solo cubre los gastos m\u00e9dicos y las reparaciones del coche. Eso es solo una peque\u00f1a parte de la indemnizaci\u00f3n a la que tiene derecho.<\/p><p>Los gastos m\u00e9dicos incluyen cada d\u00f3lar que haya gastado o vaya a gastar en el tratamiento de sus lesiones. Visitas a la sala de emergencias. Transporte en ambulancia. Cirug\u00eda. Fisioterapia. Medicamentos recetados. Citas de seguimiento. Equipo m\u00e9dico. Asesoramiento psicol\u00f3gico para superar el trauma derivado del accidente.<\/p><p>Los gastos m\u00e9dicos futuros son tan importantes como las facturas actuales. Si su m\u00e9dico le indica que necesitar\u00e1 tratamiento continuo (m\u00e1s cirug\u00edas, fisioterapia a largo plazo, control del dolor), esos costos forman parte de su reclamaci\u00f3n. La compa\u00f1\u00eda de seguros se opondr\u00e1, argumentando que el tratamiento futuro es especulativo o innecesario. Necesita expertos m\u00e9dicos que puedan documentar por qu\u00e9 se requiere ese tratamiento y cu\u00e1l ser\u00e1 su costo.<\/p><p>La p\u00e9rdida de ingresos no se limita a los cheques de pago que dej\u00f3 de percibir durante su hospitalizaci\u00f3n. Incluye cada hora de trabajo perdida debido a citas m\u00e9dicas, tiempo de recuperaci\u00f3n o discapacidad permanente. Si sus lesiones le impiden regresar al trabajo que ten\u00eda antes del accidente, puede recuperar la diferencia entre lo que ganaba antes y lo que gana ahora.<\/p><p>La indemnizaci\u00f3n por dolor y sufrimiento cubre el dolor f\u00edsico y la angustia emocional causados por el accidente. Dolor cr\u00f3nico. Ansiedad. Depresi\u00f3n. P\u00e9rdida del disfrute de la vida. La incapacidad para realizar actividades que antes disfrutaba. Estos da\u00f1os son reales, aunque no se reciban por escrito.<\/p><p>Los da\u00f1os materiales incluyen el costo de reparar o reemplazar su veh\u00edculo y cualquier art\u00edculo personal da\u00f1ado en el accidente.<\/p><p>La compa\u00f1\u00eda de seguros no le ofrecer\u00e1 una compensaci\u00f3n completa por todo esto. Minimizar\u00e1n los gastos m\u00e9dicos. Ignorar\u00e1n los costos futuros. No le ofrecer\u00e1n ninguna compensaci\u00f3n por el dolor y el sufrimiento, o intentar\u00e1n reducirla a una cantidad irrisoria. Alegar\u00e1n que usted deber\u00eda haber vuelto a trabajar antes.<\/p><p>La primera oferta de acuerdo casi nunca es justa. Es una estrategia inicial para ver si usted aceptar\u00e1 mucho menos de lo que vale su caso.<\/p><h2><strong>\u00bfQu\u00e9 sucede cuando el otro conductor no tiene seguro?<\/strong><\/h2><p>La ley de Colorado exige que los conductores tengan seguro de responsabilidad civil, pero no todos lo cumplen. Si un conductor sin seguro te atropella, no pierdes tu derecho a una indemnizaci\u00f3n, pero obtenerla se vuelve m\u00e1s complicado.<\/p><p>Aqu\u00ed es donde la cobertura para conductores sin seguro en tu propia p\u00f3liza se vuelve crucial. Esta cobertura est\u00e1 dise\u00f1ada precisamente para esta situaci\u00f3n. Entra en acci\u00f3n cuando el conductor culpable no tiene seguro para pagar tu reclamaci\u00f3n.<\/p><p>Pero aqu\u00ed est\u00e1 el problema: ahora est\u00e1s presentando una reclamaci\u00f3n contra tu propia compa\u00f1\u00eda de seguros. La aseguradora a la que has estado pagando primas durante a\u00f1os se convierte de repente en la parte que lucha contra tu reclamaci\u00f3n. Investigar\u00e1n con la misma agresividad que la otra parte. Discutir\u00e1n sobre el valor de tus lesiones. Rechazar\u00e1n la reclamaci\u00f3n, te ofrecer\u00e1n una indemnizaci\u00f3n irrisoria y te presionar\u00e1n para que llegues a un acuerdo.<\/p><p>La cobertura para conductores con seguro insuficiente funciona de la misma manera. Si el conductor culpable tiene seguro, pero no el suficiente para cubrir los da\u00f1os, su cobertura UIM puede cubrir la diferencia. Sin embargo, su aseguradora intentar\u00e1 pagar lo menos posible.<\/p><p>Necesitas un abogado que sepa c\u00f3mo gestionar las reclamaciones por conductores sin seguro o con seguro insuficiente, que entienda el lenguaje de las p\u00f3lizas que utilizan las aseguradoras para intentar denegar la cobertura y que est\u00e9 dispuesto a llevar tu caso a juicio si es necesario para obtener una indemnizaci\u00f3n completa.<\/p><h2><strong>Condiciones preexistentes y c\u00f3mo las compa\u00f1\u00edas de seguros las utilizan en su contra.<\/strong><\/h2><p>Si usted padec\u00eda alguna afecci\u00f3n m\u00e9dica antes del accidente (dolor de espalda, dolor de cuello, artritis, lesiones previas), la compa\u00f1\u00eda de seguros la utilizar\u00e1 para denegar o reducir su reclamaci\u00f3n.<\/p><p>Argumentar\u00e1n que tu dolor actual no se debe al accidente. Dir\u00e1n que solo intentas culpar al choque de problemas que ya ten\u00edas. Afirmar\u00e1n que es imposible separar la lesi\u00f3n antigua de la nueva, por lo que no deber\u00edan pagar nada.<\/p><p>Esta es una t\u00e1ctica habitual y es err\u00f3nea.<\/p><p>La ley de Colorado es clara: puede obtener una indemnizaci\u00f3n incluso si ten\u00eda una afecci\u00f3n preexistente, siempre y cuando el accidente la haya empeorado. Si le dol\u00eda la espalda antes de la colisi\u00f3n pero ahora le duele m\u00e1s, el accidente le caus\u00f3 una lesi\u00f3n adicional. Si controlaba su artritis con medicamentos ocasionales pero ahora necesita cirug\u00eda, el choque le caus\u00f3 un da\u00f1o nuevo.<\/p><p>Para demostrarlo se necesitan pruebas m\u00e9dicas. Necesita m\u00e9dicos que puedan explicar qu\u00e9 cambi\u00f3 despu\u00e9s del accidente. Necesita historiales cl\u00ednicos que muestren la diferencia entre su estado antes y despu\u00e9s. Necesita testimonios que establezcan la relaci\u00f3n de causalidad.<\/p><p>Las compa\u00f1\u00edas de seguros cuentan con que usted desconozca esto. Cuentan con que se desanime y se d\u00e9 por vencido. Cuentan con que acepte su argumento de que las enfermedades preexistentes impiden la indemnizaci\u00f3n.<\/p><h2><strong>Por qu\u00e9 firmar cualquier documento antes de hablar con un abogado es un error<\/strong><\/h2><p>La compa\u00f1\u00eda de seguros le enviar\u00e1 documentos para firmar. Autorizaciones m\u00e9dicas. Formularios de declaraci\u00f3n registrada. Liberaciones de liquidaci\u00f3n.<\/p><p>No firme nada hasta que haya hablado con un abogado.<\/p><p>Una autorizaci\u00f3n m\u00e9dica le da a la aseguradora acceso a todo su historial m\u00e9dico, no solo a los registros relacionados con el accidente. Revisar\u00e1n minuciosamente a\u00f1os de registros en busca de cualquier cosa que puedan usar para denegar o reducir su reclamaci\u00f3n. Una lesi\u00f3n antigua. Un accidente anterior. Un diagn\u00f3stico de salud mental. Cualquier cosa que pueda tergiversarse para argumentar que sus problemas actuales no se deben a este accidente.<\/p><p>Un acuerdo de liberaci\u00f3n pone fin a su caso. Una vez que lo firme, no podr\u00e1 reclamar m\u00e1s dinero, incluso si posteriormente descubre que sus lesiones son m\u00e1s graves de lo que pensaba. Incluso si necesita una cirug\u00eda que desconoc\u00eda al momento del acuerdo. Incluso si la compa\u00f1\u00eda de seguros minti\u00f3 sobre el valor de su caso.<\/p><p>La gente firma estos documentos porque el perito lo presenta como algo rutinario. Dicen que todo el mundo los firma. Dicen que es la \u00fanica manera de que tu reclamaci\u00f3n avance. Dan a entender que negarse a firmar te convierte en una persona dif\u00edcil o sospechosa.<\/p><p>Nada de eso es cierto. Usted tiene derecho a proteger su reclamaci\u00f3n. Tiene derecho a consultar con un abogado antes de proporcionar cualquier informaci\u00f3n a la compa\u00f1\u00eda de seguros.<\/p><h2><strong>Prestamos servicios a clientes en toda el \u00e1rea metropolitana de Denver.<\/strong><\/h2><p>McCormick &amp; Murphy, PC representa a clientes en toda la regi\u00f3n de Denver, incluyendo Englewood, Lakewood, Arvada, Westminster, Thornton, Wheat Ridge, Aurora, Littleton, Centennial, Greenwood Village, Highlands Ranch, Broomfield y las comunidades aleda\u00f1as. Entendemos c\u00f3mo se aplica la ley de Colorado a su caso, c\u00f3mo los tribunales locales manejan las reclamaciones por accidentes automovil\u00edsticos y qu\u00e9 t\u00e1cticas utilizan las compa\u00f1\u00edas de seguros del \u00e1rea de Denver para evitar pagar una compensaci\u00f3n justa.<\/p><p>Nuestra oficina est\u00e1 ubicada en 1547 N Gaylord St UNIT 303, Denver, CO 80206. Tambi\u00e9n brindamos servicios a clientes en Boulder, Fort Collins, Loveland, Longmont y en toda la regi\u00f3n de Front Range.<\/p><h2><strong>Qu\u00e9 esperar cuando llama<\/strong><\/h2><p>Cuando se comunique con McCormick &amp; Murphy, PC, hablar\u00e1 directamente con un abogado, no con un asistente legal, un coordinador de atenci\u00f3n al cliente ni un centro de llamadas. Le preguntaremos qu\u00e9 sucedi\u00f3, qu\u00e9 lesiones sufri\u00f3 y qu\u00e9 ha dicho o hecho la compa\u00f1\u00eda de seguros hasta el momento.<\/p><p>Le explicaremos el valor probable de su caso bas\u00e1ndonos en casos similares que hemos gestionado. Le indicaremos qu\u00e9 pruebas necesita reunir. Le asesoraremos sobre qu\u00e9 decir \u2014y qu\u00e9 no decir\u2014 a los peritos de seguros.<\/p><p>Si aceptamos su caso, lo gestionaremos bajo un acuerdo de honorarios condicionales. Usted no paga nada a menos que obtengamos una indemnizaci\u00f3n para usted. Sin cargos iniciales. Sin facturaci\u00f3n por hora. Sin cargos sorpresa.<\/p><p>Desde el momento en que nos contrata, nos encargamos de toda la comunicaci\u00f3n con las compa\u00f1\u00edas de seguros. No tendr\u00e1 que atender sus llamadas ni responder a sus preguntas. Usted se centra en su recuperaci\u00f3n. Nosotros nos centramos en preparar su caso.<\/p><h2><strong>Sus derechos no esperan<\/strong><\/h2><p>La ley de Colorado te da tres a\u00f1os a partir de la fecha del accidente para presentar una demanda por lesiones personales. Puede parecer mucho tiempo, pero no lo es.<\/p><p>Las pruebas desaparecen. Los testigos se mudan o olvidan detalles cruciales. Los historiales m\u00e9dicos se vuelven m\u00e1s dif\u00edciles de obtener. La compa\u00f1\u00eda de seguros aprovecha cada retraso para argumentar que sus lesiones no son graves; si lo fueran, usted habr\u00eda actuado antes.<\/p><p>M\u00e1s importante a\u00fan, las decisiones que tome en los primeros d\u00edas despu\u00e9s del accidente determinar\u00e1n el rumbo de su caso. Una declaraci\u00f3n grabada antes de hablar con un abogado puede perjudicar su reclamaci\u00f3n. Un acuerdo firmado demasiado pronto puede dejarle sin nada cuando descubra que sus lesiones son m\u00e1s graves de lo que pensaba.<\/p><p>La compa\u00f1\u00eda de seguros ya est\u00e1 preparando su defensa. Usted deber\u00eda estar preparando la suya.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fcd94d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcd94d0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6a760e\" data-id=\"d6a760e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7303432 elementor-widget elementor-widget-heading\" data-id=\"7303432\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Preguntas frecuentes<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3b80d4 elementor-widget elementor-widget-accordion\" data-id=\"d3b80d4\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2221\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2221\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfQu\u00e9 debo hacer inmediatamente despu\u00e9s de un accidente de coche en Englewood?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2221\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2221\"><p>Verifique si hay heridos y llame al 911 si alguien est\u00e1 lastimado. Intercambie informaci\u00f3n con el otro conductor (nombres, n\u00fameros de tel\u00e9fono, datos del seguro, n\u00fameros de matr\u00edcula), pero no hable sobre qui\u00e9n tuvo la culpa ni se disculpe. Tome fotos de los veh\u00edculos, los da\u00f1os, el estado de la carretera, las se\u00f1ales de tr\u00e1nsito y cualquier lesi\u00f3n visible. Obtenga los nombres y la informaci\u00f3n de contacto de los testigos. Si la polic\u00eda acude al lugar, obtenga el n\u00famero de reporte. Busque atenci\u00f3n m\u00e9dica incluso si se siente bien, ya que algunas lesiones no presentan s\u00edntomas de inmediato. Luego, contacte a un abogado antes de hablar con cualquier compa\u00f1\u00eda de seguros. Las decisiones que tome en las primeras 72 horas pueden determinar si obtiene una compensaci\u00f3n completa o pierde su reclamo por completo.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2222\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2222\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfTengo que dar una declaraci\u00f3n grabada a la compa\u00f1\u00eda de seguros?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2222\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2222\"><p>No. No est\u00e1 obligado a prestar declaraci\u00f3n grabada ante la compa\u00f1\u00eda de seguros del otro conductor. Se la pedir\u00e1n y la har\u00e1n parecer obligatoria, pero no lo es. Cada palabra que diga ser\u00e1 analizada en busca de cualquier cosa que pueda usarse para reducir o denegar su reclamaci\u00f3n. Incluso declaraciones inocentes, como decir que se siente bien cuando est\u00e1 en estado de shock o olvidar un detalle por estar abrumado, pueden ser tergiversadas en su contra. Su propia p\u00f3liza de seguro puede requerir que coopere con su aseguradora, pero eso no significa que deba prestar declaraci\u00f3n antes de hablar con un abogado. Contacte primero con un abogado para comprender sus derechos y obligaciones antes de hablar con nadie.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2223\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2223\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfCu\u00e1nto tiempo tengo para presentar un reclamo por lesiones personales en Colorado?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2223\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2223\"><p>En Colorado, el plazo de prescripci\u00f3n para demandas por lesiones personales es de tres a\u00f1os a partir de la fecha del accidente. Si no la presenta dentro de ese plazo, pierde su derecho a recibir una indemnizaci\u00f3n. Sin embargo, esperar demasiado genera serios problemas incluso antes de que venza el plazo. Las pruebas desaparecen, los testigos olvidan detalles y la compa\u00f1\u00eda de seguros aprovecha las demoras para argumentar que sus lesiones no son graves. Cuanto antes consulte con un abogado, m\u00e1s s\u00f3lido ser\u00e1 su caso.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2224\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2224\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfQu\u00e9 ocurre si el otro conductor no tiene seguro?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2224\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2224\"><p>A\u00fan puedes obtener una indemnizaci\u00f3n a trav\u00e9s de la cobertura para conductores sin seguro de tu propia p\u00f3liza de seguro de auto. Esta cobertura est\u00e1 dise\u00f1ada precisamente para esta situaci\u00f3n: cubre tu reclamaci\u00f3n cuando el conductor culpable no tiene seguro. El problema es que ahora est\u00e1s presentando una reclamaci\u00f3n contra tu propia aseguradora, y esta se defender\u00e1 con la misma vehemencia que la otra parte. Disputar\u00e1n la culpabilidad, cuestionar\u00e1n el valor de tus lesiones y te presionar\u00e1n para que aceptes un acuerdo por menos de lo que vale tu caso. Un abogado puede negociar con tu aseguradora y luchar por una indemnizaci\u00f3n completa bajo tu cobertura para conductores sin seguro.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2225\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2225\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfPuedo obtener una indemnizaci\u00f3n si tuve parte de la culpa del accidente?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2225\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2225\"><p>S\u00ed, siempre y cuando su responsabilidad sea inferior al 50 %. Colorado aplica una regla de negligencia comparativa modificada. Si usted fue responsable en un 30 % del accidente, su indemnizaci\u00f3n se reduce en un 30 %. Si su responsabilidad fue del 49 %, a\u00fan recibir\u00e1 una indemnizaci\u00f3n, aunque reducida en un 49 %. Pero si se determina que su responsabilidad es del 50 % o m\u00e1s, no recibir\u00e1 ninguna indemnizaci\u00f3n. Las compa\u00f1\u00edas de seguros lo saben e intentar\u00e1n culparle incluso cuando su conductor haya sido claramente responsable del accidente. El objetivo es reducir su indemnizaci\u00f3n o eliminarla por completo. Para proteger su reclamaci\u00f3n, se requieren pruebas que demuestren la culpa del otro conductor.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2226\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2226\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfCu\u00e1nto vale mi caso de accidente de coche?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2226\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2226\"><p>El valor depende de la gravedad de sus lesiones, el costo de su tratamiento m\u00e9dico, la cantidad de d\u00edas de trabajo perdidos, si tiene una discapacidad permanente y el impacto en su vida. Los gastos m\u00e9dicos, la p\u00e9rdida de ingresos, los costos de tratamientos futuros, el dolor y el sufrimiento, y los da\u00f1os a la propiedad se tienen en cuenta en el c\u00e1lculo. Ning\u00fan abogado puede darle una cifra exacta al inicio del caso; el monto total de sus da\u00f1os puede no estar claro hasta que finalice su tratamiento. Sin embargo, un abogado con experiencia puede estimar un rango bas\u00e1ndose en casos similares y decirle si la oferta de la compa\u00f1\u00eda de seguros es justa o un insulto. La primera oferta de acuerdo casi nunca refleja el valor real de su caso.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2227\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2227\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfMi propia compa\u00f1\u00eda de seguros luchar\u00e1 en mi contra?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2227\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2227\"><p>A veces, s\u00ed. Si presenta una reclamaci\u00f3n bajo su cobertura de automovilista sin seguro o con seguro insuficiente, en realidad est\u00e1 presentando una reclamaci\u00f3n contra su propia p\u00f3liza. Su aseguradora se convierte en la parte que lucha contra su reclamaci\u00f3n. Investigar\u00e1 sus lesiones, disputar\u00e1 el valor de sus da\u00f1os y lo presionar\u00e1 para que acepte un acuerdo por menos. Incluso cuando no presenta una reclamaci\u00f3n por automovilista sin seguro o con seguro insuficiente, su propia aseguradora puede crear obst\u00e1culos: retrasar la cobertura de los gastos m\u00e9dicos, discutir sobre los l\u00edmites de la p\u00f3liza o presionarlo para que llegue a un acuerdo con la aseguradora del conductor culpable para que no tenga que pagar las prestaciones por automovilista con seguro insuficiente. Las compa\u00f1\u00edas de seguros son empresas. Su objetivo es minimizar lo que pagan, incluso a sus propios asegurados.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b45fbd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b45fbd8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c395d74\" data-id=\"c395d74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-577dbb57 elementor-widget elementor-widget-heading\" data-id=\"577dbb57\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfLesionado en un accidente? \u00a1Cont\u00e1ctenos hoy!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b0af151 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1b0af151\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3663b52b elementor-widget elementor-widget-text-editor\" data-id=\"3663b52b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a1Rellena el formulario y nos pondremos en contacto contigo lo antes posible!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44d4dcf elementor-button-align-start elementor-widget elementor-widget-global elementor-global-4170 elementor-widget-form\" data-id=\"44d4dcf\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.19.0 - 05-02-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"11982\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"44d4dcf\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"McCormick &amp; Murphy &#8211; Personal Injury Lawyers\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nombre completo\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_7e89de5 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_7e89de5]\" id=\"form-field-field_7e89de5\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"N\u00famero de tel\u00e9fono\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"S\u00f3lo se aceptan n\u00fameros y caracteres telef\u00f3nicos (#, -, *, etc.).\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-field_776ba71 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[field_776ba71]\" id=\"form-field-field_776ba71\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-field_baef31a elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_baef31a\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tUbicaci\u00f3n\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Colorado Springs\" id=\"form-field-field_baef31a-0\" name=\"form_fields[field_baef31a][]\"> <label for=\"form-field-field_baef31a-0\">Colorado Springs<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Denver\" id=\"form-field-field_baef31a-1\" name=\"form_fields[field_baef31a][]\"> <label for=\"form-field-field_baef31a-1\">Denver<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Pueblo\" id=\"form-field-field_baef31a-2\" name=\"form_fields[field_baef31a][]\"> <label for=\"form-field-field_baef31a-2\">Pueblo<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-field_f44c0f9 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f44c0f9\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u00c1rea de especialidad\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Car Accident\" id=\"form-field-field_f44c0f9-0\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-0\">Accidente de coche<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Motorcycle Accident\" id=\"form-field-field_f44c0f9-1\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-1\">Accidente de motocicleta<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Wrongful Death\" id=\"form-field-field_f44c0f9-2\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-2\">Muerte por negligencia<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Slip &amp; Fall\" id=\"form-field-field_f44c0f9-3\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-3\">Resbal\u00f3n y ca\u00edda<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Insurance Bad Faith\" id=\"form-field-field_f44c0f9-4\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-4\">Mala fe en seguros<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Dog Bite\" id=\"form-field-field_f44c0f9-5\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-5\">Mordedura de perro<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Traumatic Brain Injury\" id=\"form-field-field_f44c0f9-6\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-6\">Lesi\u00f3n cerebral traum\u00e1tica<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Other\" id=\"form-field-field_f44c0f9-7\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-7\">Otro<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensaje\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_923baa2 elementor-col-100 recaptcha_v3-bottomleft\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_923baa2\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfpixwqAAAAALY-qrx12rHzDvD4l8AL_-lvT7XT\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomleft\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar ahora<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cd45637 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cd45637\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-75bfb91f\" data-id=\"75bfb91f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e6e38d3 elementor-widget elementor-widget-heading\" data-id=\"4e6e38d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Colorado Springs<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b03e91f elementor-widget elementor-widget-text-editor\" data-id=\"2b03e91f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>929 W Colorado Ave,<br \/>Colorado Springs, Colorado<br \/>80905<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2906e2ba elementor-widget elementor-widget-heading\" data-id=\"2906e2ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"e-add-hoverheading elementor-heading-title elementor-size-default\"><a href=\"tel:719-389-0400\">Tel\u00e9fono: (719)-389-0400<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42071306 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"42071306\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/maps.app.goo.gl\/kojCLybzxiurNg5JA\" title=\"Abogados de lesiones personales en Colorado Springs\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtener direcciones<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1cebae7d\" data-id=\"1cebae7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-519dc941 elementor-widget elementor-widget-heading\" data-id=\"519dc941\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pueblo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d617992 elementor-widget elementor-widget-text-editor\" data-id=\"1d617992\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>301 N. Calle principal,<br \/>Pueblo, Colorado<br \/>81003<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ada7dfd elementor-widget elementor-widget-heading\" data-id=\"7ada7dfd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"e-add-hoverheading elementor-heading-title elementor-size-default\"><a href=\"tel:(888)-668-1182\">Tel\u00e9fono: (888)-668-1182<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27c1a0f6 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"27c1a0f6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/maps.app.goo.gl\/eirbTTn8gtvYxwm98\" title=\"Abogados de lesiones personales en Pueblo\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtener direcciones<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-206a66c4\" data-id=\"206a66c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-198b22e7 elementor-widget elementor-widget-heading\" data-id=\"198b22e7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Denver<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57637af6 elementor-widget elementor-widget-text-editor\" data-id=\"57637af6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"text_block-107-192\" class=\"ct-text-block\">1547 N. Gaylord St.,<br \/>Unidad 303<br \/>Denver, Colorado 80206<\/div><div id=\"div_block-98-192\" class=\"ct-div-block\"><div id=\"text_block-99-192\" class=\"ct-text-block phone-cont\">\u00a0<\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-106eddcc elementor-widget elementor-widget-heading\" data-id=\"106eddcc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"e-add-hoverheading elementor-heading-title elementor-size-default\"><a href=\"tel:(888)-668-1182\">Tel\u00e9fono: (888)-668-1182<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dbdbfa6 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"1dbdbfa6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/maps.app.goo.gl\/y9gVVznr14hyoWwr9\" title=\"Abogados de lesiones personales en Denver\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtener direcciones<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f158b3e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f158b3e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-376f6465\" data-id=\"376f6465\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-34df6e5b\" data-id=\"34df6e5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14326b06 elementor-widget elementor-widget-image\" data-id=\"14326b06\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"372\" height=\"113\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/09\/mccormick-logo-new.png\" class=\"attachment-large size-large wp-image-975\" alt=\"\" srcset=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/09\/mccormick-logo-new.png 372w, https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/09\/mccormick-logo-new-300x91.png 300w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e6f3c14\" data-id=\"e6f3c14\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eb757dc elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eb757dc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-e-bg-lazyload=\"\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2cf2460\" data-id=\"2cf2460\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-38df2d90\" data-id=\"38df2d90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c7dfba7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7dfba7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-45435a85\" data-id=\"45435a85\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e553e22 elementor-widget elementor-widget-image\" data-id=\"2e553e22\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"49\" height=\"49\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2024\/02\/twitter-gold.png\" class=\"attachment-large size-large wp-image-2571\" alt=\"\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-254412d\" data-id=\"254412d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f0fdd1b elementor-widget elementor-widget-image\" data-id=\"2f0fdd1b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/McCormickMurphy\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"49\" height=\"49\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2024\/02\/fb-gold.png\" class=\"attachment-large size-large wp-image-2572\" alt=\"\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3557e7da\" data-id=\"3557e7da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-358d4458 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"358d4458\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78a5b04a\" data-id=\"78a5b04a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16f02e34 elementor-widget elementor-widget-heading\" data-id=\"16f02e34\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Opina sobre nosotros en Google<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34ff68ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34ff68ac\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-25598db0\" data-id=\"25598db0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-628fa815 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"628fa815\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.google.com\/search?q=McCormick+%26+Murphy%2C+P.C.+Colorado+Springs&#038;sca_esv=582393838&#038;rlz=1C1CHBD_enUS941US943&#038;ei=m-tTZZn7AcmoqtsP7rmt8Ao&#038;ved=0ahUKEwjZtLmuvMSCAxVJlGoFHe5cC64Q4dUDCBA&#038;uact=5&#038;oq=McCormick+%26+Murphy%2C+P.C.+Colorado+Springs&#038;gs_lp=Egxnd3Mtd2l6LXNlcnAiKU1jQ29ybWljayAmIE11cnBoeSwgUC5DLiBDb2xvcmFkbyBTcHJpbmdzMgUQABiiBDIFEAAYogQyBRAAGKIESLIhUO4GWN0fcAJ4AJABAJgBrgGgAaQMqgEEMTMuM7gBA8gBAPgBAcICAhAm4gMEGAEgQYgGAQ&#038;sclient=gws-wiz-serp#lrd=0x8713453243ee88c7:0x89c7f2c6c084c442,1,,,,\" title=\"Rese\u00f1a de abogados de lesiones personales de Colorado Springs\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Colorado Springs<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-36b0459\" data-id=\"36b0459\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26eb6bc1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"26eb6bc1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.google.com\/search?q=McCormick+%26+Murphy%2C+P.C.+Pueblo&#038;sca_esv=582393838&#038;rlz=1C1CHBD_enUS941US943&#038;ei=4-tTZfrTN4ncqtsPxLaHYA&#038;ved=0ahUKEwi60ZnRvMSCAxUJrmoFHUTbAQwQ4dUDCBA&#038;uact=5&#038;oq=McCormick+%26+Murphy%2C+P.C.+Pueblo&#038;gs_lp=Egxnd3Mtd2l6LXNlcnAiH01jQ29ybWljayAmIE11cnBoeSwgUC5DLiBQdWVibG8yBRAhGKABMgUQIRigAUjCJFC0FFjmH3ADeAGQAQCYAYMBoAHOBKoBAzQuMrgBA8gBAPgBAcICChAAGEcY1gQYsAPCAgIQJuIDBBgAIEGIBgGQBgI&#038;sclient=gws-wiz-serp#lrd=0x8713a303b247ef69:0x94b2cd814dfabe26,1,,,,\" title=\"Rese\u00f1a de los abogados de lesiones personales de Pueblo\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Pueblo<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-282f7c35\" data-id=\"282f7c35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c450e1f elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"3c450e1f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.google.com\/search?q=McCormick+%26+Murphy%2C+P.C.+Denver&#038;sca_esv=582393838&#038;rlz=1C1CHBD_enUS941US943&#038;ei=-utTZb79GZCpqtsPt7-JmAY&#038;ved=0ahUKEwi-4vfbvMSCAxWQlGoFHbdfAmMQ4dUDCBA&#038;uact=5&#038;oq=McCormick+%26+Murphy%2C+P.C.+Denver&#038;gs_lp=Egxnd3Mtd2l6LXNlcnAiH01jQ29ybWljayAmIE11cnBoeSwgUC5DLiBEZW52ZXIyAhAmSPYNUIwHWKgMcAJ4AJABAJgBVaABzQOqAQE2uAEDyAEA-AEBwgIIEAAYogQYsAPiAwQYASBBiAYBkAYC&#038;sclient=gws-wiz-serp#lrd=0x876c7eb5457a815b:0x993bb4fecef454ff,1,,,,\" title=\"Rese\u00f1a de abogados especializados en lesiones personales en Denver\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Denver<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53dc1c34 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53dc1c34\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1815f46\" data-id=\"1815f46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a874abf elementor-widget elementor-widget-text-editor\" data-id=\"4a874abf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Descargo de responsabilidad: La informaci\u00f3n que se incluye en este sitio web es solo para fines informativos. Este sitio web no debe tomarse como asesoramiento legal. Los resultados anteriores no garantizan un resultado similar. Esta informaci\u00f3n no debe tomarse como la formaci\u00f3n de una relaci\u00f3n abogado-cliente.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61498143 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"61498143\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a86cf9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a86cf9b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68ee5420\" data-id=\"68ee5420\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e674cd4 elementor-widget elementor-widget-text-editor\" data-id=\"7e674cd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a9\u00a0<span id=\"span-97-46\" class=\"ct-span\">2026<\/span>\u00a0McCormick &amp; Murphy, PC | Todos los derechos reservados |\u00a0<a href=\"https:\/\/mccormickmurphy.com\/es\/privacy-policy\/\">pol\u00edtica de privacidad<\/a>\u00a0|\u00a0<a href=\"https:\/\/mccormickmurphy.com\/es\/terms-and-conditions\/\">T\u00e9rminos y condiciones<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Colorado Springs Pueblo Denver Call (888)-668-1182 Auto Accident Lawyer Englewood The insurance adjuster calls before you even get home from the hospital. They sound friendly. They say they just want to help. They ask if you can give a quick recorded statement\u2014just to get the process moving. This is not help. This is strategy. The &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/mccormickmurphy.com\/es\/auto-accident-lawyer-englewood\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Auto Accident Lawyer Englewood&#8221;<\/span><\/a><\/p>","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-11982","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Auto Accident Lawyer Englewood - McCormick &amp; Murphy - Personal Injury Lawyers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mccormickmurphy.com\/es\/auto-accident-lawyer-englewood\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auto Accident Lawyer Englewood\" \/>\n<meta property=\"og:description\" content=\"Colorado Springs Pueblo Denver Call (888)-668-1182 Auto Accident Lawyer Englewood The insurance adjuster calls before you even get home from the hospital. They sound friendly. They say they just want to help. They ask if you can give a quick recorded statement\u2014just to get the process moving. This is not help. This is strategy. The &hellip; Continuar leyendo &quot;Auto Accident Lawyer Englewood&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mccormickmurphy.com\/es\/auto-accident-lawyer-englewood\/\" \/>\n<meta property=\"og:site_name\" content=\"McCormick &amp; Murphy - Personal Injury Lawyers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T15:50:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/\",\"url\":\"https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/\",\"name\":\"Auto Accident Lawyer Englewood - McCormick &amp; Murphy - Personal Injury Lawyers\",\"isPartOf\":{\"@id\":\"https:\/\/mccormickmurphy.com\/#website\"},\"datePublished\":\"2026-05-17T23:51:35+00:00\",\"dateModified\":\"2026-06-22T15:50:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mccormickmurphy.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auto Accident Lawyer Englewood\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mccormickmurphy.com\/#website\",\"url\":\"https:\/\/mccormickmurphy.com\/\",\"name\":\"McCormick &amp; Murphy - Personal Injury Lawyers\",\"description\":\"Premier Colorado Personal Injury Lawyers\",\"publisher\":{\"@id\":\"https:\/\/mccormickmurphy.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mccormickmurphy.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mccormickmurphy.com\/#organization\",\"name\":\"McCormick & Murphy, P.C.\",\"url\":\"https:\/\/mccormickmurphy.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mccormickmurphy.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png\",\"contentUrl\":\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png\",\"width\":261,\"height\":80,\"caption\":\"McCormick & Murphy, P.C.\"},\"image\":{\"@id\":\"https:\/\/mccormickmurphy.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Auto Accident Lawyer Englewood - McCormick &amp; Murphy - Personal Injury Lawyers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mccormickmurphy.com\/es\/auto-accident-lawyer-englewood\/","og_locale":"es_MX","og_type":"article","og_title":"Auto Accident Lawyer Englewood","og_description":"Colorado Springs Pueblo Denver Call (888)-668-1182 Auto Accident Lawyer Englewood The insurance adjuster calls before you even get home from the hospital. They sound friendly. They say they just want to help. They ask if you can give a quick recorded statement\u2014just to get the process moving. This is not help. This is strategy. The &hellip; Continuar leyendo \"Auto Accident Lawyer Englewood\"","og_url":"https:\/\/mccormickmurphy.com\/es\/auto-accident-lawyer-englewood\/","og_site_name":"McCormick &amp; Murphy - Personal Injury Lawyers","article_modified_time":"2026-06-22T15:50:12+00:00","og_image":[{"url":"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/","url":"https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/","name":"Auto Accident Lawyer Englewood - McCormick &amp; Murphy - Personal Injury Lawyers","isPartOf":{"@id":"https:\/\/mccormickmurphy.com\/#website"},"datePublished":"2026-05-17T23:51:35+00:00","dateModified":"2026-06-22T15:50:12+00:00","breadcrumb":{"@id":"https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mccormickmurphy.com\/auto-accident-lawyer-englewood\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mccormickmurphy.com\/"},{"@type":"ListItem","position":2,"name":"Auto Accident Lawyer Englewood"}]},{"@type":"WebSite","@id":"https:\/\/mccormickmurphy.com\/#website","url":"https:\/\/mccormickmurphy.com\/","name":"McCormick &amp; Murphy - Abogados de lesiones personales","description":"Abogados de lesiones personales de primer nivel en Colorado","publisher":{"@id":"https:\/\/mccormickmurphy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mccormickmurphy.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mccormickmurphy.com\/#organization","name":"McCormick y Murphy, PC","url":"https:\/\/mccormickmurphy.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mccormickmurphy.com\/#\/schema\/logo\/image\/","url":"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png","contentUrl":"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png","width":261,"height":80,"caption":"McCormick & Murphy, P.C."},"image":{"@id":"https:\/\/mccormickmurphy.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/comments?post=11982"}],"version-history":[{"count":7,"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11982\/revisions"}],"predecessor-version":[{"id":12448,"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11982\/revisions\/12448"}],"wp:attachment":[{"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/media?parent=11982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}