{"id":11727,"date":"2026-05-14T08:40:52","date_gmt":"2026-05-14T14:40:52","guid":{"rendered":"https:\/\/mccormickmurphy.com\/?page_id=11727"},"modified":"2026-06-22T10:40:52","modified_gmt":"2026-06-22T16:40:52","slug":"westminster-dog-bite-lawyer","status":"publish","type":"page","link":"https:\/\/mccormickmurphy.com\/es\/westminster-dog-bite-lawyer\/","title":{"rendered":"Abogado especializado en mordeduras de perro en Westminster"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"11727\" class=\"elementor elementor-11727\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eb8eac6 elementor-section-content-middle elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eb8eac6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5998f8d1\" data-id=\"5998f8d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d2c067c elementor-icon-list--layout-inline elementor-mobile-align-center elementor-tablet-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5d2c067c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/mccormickmurphy.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/kojCLybzxiurNg5JA\" title=\"Abogados de lesiones personales en Colorado Springs\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Colorado Springs<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/eirbTTn8gtvYxwm98\" title=\"Abogados de lesiones personales en Pueblo\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pueblo<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/y9gVVznr14hyoWwr9\" title=\"Abogados de lesiones personales en Denver\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Denver<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-56e4805c elementor-hidden-phone elementor-hidden-tablet\" data-id=\"56e4805c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29771d7c elementor-widget elementor-widget-heading\" data-id=\"29771d7c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><p class=\"e-add-hoverheading elementor-heading-title elementor-size-default\"><a href=\"tel:%20(888)-668-1182\">Llama al (888)-668-1182<\/a><\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bd0d5d9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bd0d5d9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3c30dc41\" data-id=\"3c30dc41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd93757 elementor-widget elementor-widget-image\" data-id=\"cd93757\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/es\/\" title=\"Abogados de lesiones personales en Colorado\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"261\" height=\"80\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png\" class=\"attachment-full size-full wp-image-136\" alt=\"Personal Injury Lawyers Colorado\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7cd49a88\" data-id=\"7cd49a88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fe93ca3 elementor-nav-menu__align-end elementor-nav-menu--stretch elementor-nav-menu--dropdown-mobile elementor-nav-menu__text-align-center elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"6fe93ca3\" data-element_type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/mccormickmurphy.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-nav-menu.min.css\">\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-text e--animation-sink\">\n\t\t\t\t<ul id=\"menu-1-6fe93ca3\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1028\"><a href=\"\/es\/\" title=\"Abogados de lesiones personales | Colorado\" class=\"elementor-item\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/11\/small-white-house-icon.png\"  \/><\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-131\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/\" title=\"Acerca de nuestros abogados especializados en lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-item\">Acerca de<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-198\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/kirk-mccormick\/\" title=\"Kirk McCormick | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\">Kirk McCormick<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-202\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/james-murphy\/\" title=\"James Murphy | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\">James Murphy<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-206\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/sample-case-result\/\" title=\"Resultado de un caso de muestra | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\">Resultado de un caso de muestra<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-209\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/m-m-in-the-community\/\" title=\"En la comunidad | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">M + M en la comunidad<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-220\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/testimonials\/\" title=\"Testimonios | Abogados de lesiones personales | Colorado\" class=\"elementor-sub-item\">Testimonios<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-134\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/\" title=\"\u00c1reas de pr\u00e1ctica | Abogados de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\">\u00c1reas de pr\u00e1ctica<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-219\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/\" title=\"Abogado de accidentes de tr\u00e1fico | Abogado de accidentes de tr\u00e1fico | Colorado Springs\" class=\"elementor-sub-item\">Accidentes de tr\u00e1fico<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-236\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-distracted-driving-accident-lawyer\/\" title=\"Abogado de conducci\u00f3n distra\u00edda en Colorado Springs\" class=\"elementor-sub-item\">Conducci\u00f3n distra\u00edda<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-244\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-drunk-driving-accident-lawyers\/\" title=\"Abogado de accidentes por conducir ebrio en Colorado Springs\" class=\"elementor-sub-item\">Conductor ebrio<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-252\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-failure-to-yield-right-of-way-accident-lawyers\/\" title=\"Abogado de accidentes por no ceder el paso en Colorado Springs\" class=\"elementor-sub-item\">No ceder<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-263\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-head-on-truck-and-car-accident-lawyers\/\" title=\"Abogado de accidentes de tr\u00e1fico de frente en Colorado Springs\" class=\"elementor-sub-item\">Accidentes frontales<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-285\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-hit-and-run-accident-lawyers\/\" title=\"Abogado de accidentes de choque y fuga en Colorado Springs\" class=\"elementor-sub-item\">Choque y fuga<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-294\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-intersection-accident-lawyers\/\" title=\"Abogados de accidentes en intersecciones en Colorado Springs\" class=\"elementor-sub-item\">Accidentes en intersecciones<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-297\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-multi-vehicle-accident-pileups-lawyers\/\" title=\"Abogado de accidentes automovil\u00edsticos m\u00faltiples en Colorado Springs\" class=\"elementor-sub-item\">Accidentes de varios veh\u00edculos<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-306\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-reckless-driving-accident-lawyers\/\" title=\"Abogado de accidentes por conducci\u00f3n imprudente en Colorado Springs\" class=\"elementor-sub-item\">Accidentes por conducci\u00f3n imprudente<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-362\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-scooter-accident-lawyers\/\" title=\"Abogado de accidentes de patinetes el\u00e9ctricos en Colorado Springs\" class=\"elementor-sub-item\">Accidentes de scooter<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-319\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/motorcycle-accidents\/\" title=\"Abogados de accidentes de motocicleta en Colorado Springs\" class=\"elementor-sub-item\">Accidentes de motocicleta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-326\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/wrongful-death\/\" title=\"Abogado de muerte por negligencia en Colorado Springs\" class=\"elementor-sub-item\">Muerte por negligencia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-329\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/slip-fall-accidents\/\" title=\"Abogado de resbalones y ca\u00eddas en Colorado Springs\" class=\"elementor-sub-item\">Accidentes por resbalones y ca\u00eddas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-332\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/insurance-bad-faith\/\" title=\"Abogado de mala fe en seguros en Colorado Springs\" class=\"elementor-sub-item\">Mala fe en seguros<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-338\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/dog-bite\/\" title=\"Abogado de lesiones por mordedura de perro en Colorado Springs\" class=\"elementor-sub-item\">Mordedura de perro<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-347\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/traumatic-brain-injuries\/\" title=\"Abogado de lesiones cerebrales traum\u00e1ticas en Colorado Springs\" class=\"elementor-sub-item\">Lesiones cerebrales traum\u00e1ticas<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-132\"><a href=\"https:\/\/mccormickmurphy.com\/es\/areas-we-serve\/\" title=\"\u00c1reas en las que prestamos servicios | Abogados de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\">Ubicaciones<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-381\"><a href=\"https:\/\/mccormickmurphy.com\/es\/\" title=\"Abogados de lesiones personales | Colorado Springs\" class=\"elementor-sub-item\">Colorado Springs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-380\"><a href=\"https:\/\/mccormickmurphy.com\/es\/denver-personal-injury-attorneys\/\" title=\"Abogados de lesiones personales | Denver\" class=\"elementor-sub-item\">Denver<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-373\"><a href=\"https:\/\/mccormickmurphy.com\/es\/pueblo-personal-injury-attorneys\/\" title=\"Abogados de lesiones personales | Pueblo\" class=\"elementor-sub-item\">Pueblo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-397\"><a title=\"Recursos | McCormick &amp; Murphy, PC\" class=\"elementor-item\">Recursos<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-440\"><a href=\"https:\/\/mccormickmurphy.com\/es\/accident-reports\/\" title=\"Informes de accidentes policiales | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Obtenga su informe de accidente<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-558\"><a href=\"https:\/\/mccormickmurphy.com\/es\/hire-attorney\/\" title=\"Preguntas frecuentes sobre la contrataci\u00f3n de un abogado | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Preguntas frecuentes sobre la contrataci\u00f3n de un abogado<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-634\"><a href=\"https:\/\/mccormickmurphy.com\/es\/bad-faith-faqs\/\" title=\"Preguntas que debe hacerle a un abogado especializado en lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Preguntas frecuentes sobre lesiones personales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-562\"><a href=\"https:\/\/mccormickmurphy.com\/es\/auto-settlement\/\" title=\"Maximice la liquidaci\u00f3n de su seguro de autom\u00f3vil | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Preguntas frecuentes sobre accidentes automovil\u00edsticos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-637\"><a href=\"https:\/\/mccormickmurphy.com\/es\/video-center\/\" title=\"Centro de video | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\">Centro de video<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-396\"><a href=\"https:\/\/mccormickmurphy.com\/es\/blog\/\" title=\"Blog | Abogados de lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-item\">Blog<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-102\"><a href=\"https:\/\/mccormickmurphy.com\/es\/contact-us\/\" title=\"Cont\u00e1ctenos | Abogado de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\">Contacto<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-7358\"><a href=\"https:\/\/clients.clio.com\/login\" class=\"elementor-item\">Portal del cliente<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-7309\"><a href=\"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11727\" class=\"elementor-item elementor-item-anchor\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_US.png\" width=\"18\" height=\"12\" alt=\"en_US\" title=\"English\"><span class=\"trp-ls-language-name\">English<\/span><\/span><\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Alternar men\u00fa\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Men\u00fa<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-6fe93ca3\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1028\"><a href=\"\/es\/\" title=\"Abogados de lesiones personales | Colorado\" class=\"elementor-item\" tabindex=\"-1\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/11\/small-white-house-icon.png\"  \/><\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-131\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/\" title=\"Acerca de nuestros abogados especializados en lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-item\" tabindex=\"-1\">Acerca de<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-198\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/kirk-mccormick\/\" title=\"Kirk McCormick | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\" tabindex=\"-1\">Kirk McCormick<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-202\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/james-murphy\/\" title=\"James Murphy | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\" tabindex=\"-1\">James Murphy<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-206\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/sample-case-result\/\" title=\"Resultado de un caso de muestra | Abogado de lesiones personales | Colorado\" class=\"elementor-sub-item\" tabindex=\"-1\">Resultado de un caso de muestra<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-209\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/m-m-in-the-community\/\" title=\"En la comunidad | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">M + M en la comunidad<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-220\"><a href=\"https:\/\/mccormickmurphy.com\/es\/about\/testimonials\/\" title=\"Testimonios | Abogados de lesiones personales | Colorado\" class=\"elementor-sub-item\" tabindex=\"-1\">Testimonios<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-134\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/\" title=\"\u00c1reas de pr\u00e1ctica | Abogados de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\" tabindex=\"-1\">\u00c1reas de pr\u00e1ctica<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-219\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/\" title=\"Abogado de accidentes de tr\u00e1fico | Abogado de accidentes de tr\u00e1fico | Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes de tr\u00e1fico<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-236\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-distracted-driving-accident-lawyer\/\" title=\"Abogado de conducci\u00f3n distra\u00edda en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Conducci\u00f3n distra\u00edda<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-244\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-drunk-driving-accident-lawyers\/\" title=\"Abogado de accidentes por conducir ebrio en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Conductor ebrio<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-252\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-failure-to-yield-right-of-way-accident-lawyers\/\" title=\"Abogado de accidentes por no ceder el paso en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">No ceder<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-263\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-head-on-truck-and-car-accident-lawyers\/\" title=\"Abogado de accidentes de tr\u00e1fico de frente en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes frontales<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-285\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-hit-and-run-accident-lawyers\/\" title=\"Abogado de accidentes de choque y fuga en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Choque y fuga<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-294\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-intersection-accident-lawyers\/\" title=\"Abogados de accidentes en intersecciones en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes en intersecciones<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-297\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-multi-vehicle-accident-pileups-lawyers\/\" title=\"Abogado de accidentes automovil\u00edsticos m\u00faltiples en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes de varios veh\u00edculos<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-306\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-reckless-driving-accident-lawyers\/\" title=\"Abogado de accidentes por conducci\u00f3n imprudente en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes por conducci\u00f3n imprudente<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-362\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/auto-accidents\/colorado-springs-scooter-accident-lawyers\/\" title=\"Abogado de accidentes de patinetes el\u00e9ctricos en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes de scooter<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-319\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/motorcycle-accidents\/\" title=\"Abogados de accidentes de motocicleta en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes de motocicleta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-326\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/wrongful-death\/\" title=\"Abogado de muerte por negligencia en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Muerte por negligencia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-329\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/slip-fall-accidents\/\" title=\"Abogado de resbalones y ca\u00eddas en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Accidentes por resbalones y ca\u00eddas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-332\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/insurance-bad-faith\/\" title=\"Abogado de mala fe en seguros en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Mala fe en seguros<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-338\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/dog-bite\/\" title=\"Abogado de lesiones por mordedura de perro en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Mordedura de perro<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-347\"><a href=\"https:\/\/mccormickmurphy.com\/es\/practice-areas\/traumatic-brain-injuries\/\" title=\"Abogado de lesiones cerebrales traum\u00e1ticas en Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Lesiones cerebrales traum\u00e1ticas<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-132\"><a href=\"https:\/\/mccormickmurphy.com\/es\/areas-we-serve\/\" title=\"\u00c1reas en las que prestamos servicios | Abogados de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\" tabindex=\"-1\">Ubicaciones<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-381\"><a href=\"https:\/\/mccormickmurphy.com\/es\/\" title=\"Abogados de lesiones personales | Colorado Springs\" class=\"elementor-sub-item\" tabindex=\"-1\">Colorado Springs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-380\"><a href=\"https:\/\/mccormickmurphy.com\/es\/denver-personal-injury-attorneys\/\" title=\"Abogados de lesiones personales | Denver\" class=\"elementor-sub-item\" tabindex=\"-1\">Denver<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-373\"><a href=\"https:\/\/mccormickmurphy.com\/es\/pueblo-personal-injury-attorneys\/\" title=\"Abogados de lesiones personales | Pueblo\" class=\"elementor-sub-item\" tabindex=\"-1\">Pueblo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-397\"><a title=\"Recursos | McCormick &amp; Murphy, PC\" class=\"elementor-item\" tabindex=\"-1\">Recursos<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-440\"><a href=\"https:\/\/mccormickmurphy.com\/es\/accident-reports\/\" title=\"Informes de accidentes policiales | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Obtenga su informe de accidente<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-558\"><a href=\"https:\/\/mccormickmurphy.com\/es\/hire-attorney\/\" title=\"Preguntas frecuentes sobre la contrataci\u00f3n de un abogado | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Preguntas frecuentes sobre la contrataci\u00f3n de un abogado<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-634\"><a href=\"https:\/\/mccormickmurphy.com\/es\/bad-faith-faqs\/\" title=\"Preguntas que debe hacerle a un abogado especializado en lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Preguntas frecuentes sobre lesiones personales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-562\"><a href=\"https:\/\/mccormickmurphy.com\/es\/auto-settlement\/\" title=\"Maximice la liquidaci\u00f3n de su seguro de autom\u00f3vil | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Preguntas frecuentes sobre accidentes automovil\u00edsticos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-637\"><a href=\"https:\/\/mccormickmurphy.com\/es\/video-center\/\" title=\"Centro de video | McCormick &amp; Murphy, PC\" class=\"elementor-sub-item\" tabindex=\"-1\">Centro de video<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-396\"><a href=\"https:\/\/mccormickmurphy.com\/es\/blog\/\" title=\"Blog | Abogados de lesiones personales | McCormick &amp; Murphy, PC\" class=\"elementor-item\" tabindex=\"-1\">Blog<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-102\"><a href=\"https:\/\/mccormickmurphy.com\/es\/contact-us\/\" title=\"Cont\u00e1ctenos | Abogado de lesiones personales | McCormick &amp; Murphy\" class=\"elementor-item\" tabindex=\"-1\">Contacto<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-7358\"><a href=\"https:\/\/clients.clio.com\/login\" class=\"elementor-item\" tabindex=\"-1\">Portal del cliente<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-7309\"><a href=\"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11727\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_US.png\" width=\"18\" height=\"12\" alt=\"en_US\" title=\"English\"><span class=\"trp-ls-language-name\">English<\/span><\/span><\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5863c24b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5863c24b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-e-bg-lazyload=\"\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73ee97df\" data-id=\"73ee97df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49df690b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49df690b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f0cf89a\" data-id=\"1f0cf89a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ebd8e2a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"6ebd8e2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Abogado especializado en mordeduras de perro en Westminster<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69114856 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"69114856\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1dc00b1c\" data-id=\"1dc00b1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3aec6d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3aec6d7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ddacf6\" data-id=\"0ddacf6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46f49b2 elementor-widget elementor-widget-text-editor\" data-id=\"46f49b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>La mordedura de un perro lo cambia todo en un instante. Un momento est\u00e1s paseando a tu perro, saludando a un vecino o viendo a tu hijo jugar afuera. Al siguiente, est\u00e1s sangrando, con dolor, intentando comprender lo que acaba de suceder. Si el perro pertenece a alguien que conoces \u2014un vecino, un amigo, alguien cuya casa visitan tus hijos\u2014 la confusi\u00f3n se intensifica a\u00fan m\u00e1s.<\/p><p>Te preguntas si siquiera tienes derecho a actuar. Te preocupa que la situaci\u00f3n se vuelva inc\u00f3moda. Repasas el momento en tu cabeza, pregunt\u00e1ndote si podr\u00edas haber hecho algo diferente.<\/p><p>Esto es lo que debes saber: en Colorado, los due\u00f1os de perros son responsables de sus animales. La lesi\u00f3n que t\u00fa o tu hijo sufrieron es real. El trauma es real. Y las facturas m\u00e9dicas, la p\u00e9rdida de ingresos y el impacto psicol\u00f3gico no desaparecen solo porque el perro &quot;nunca haya hecho esto antes&quot; o porque conozcas al due\u00f1o.<\/p><p>En McCormick &amp; Murphy, PC, representamos a personas en Westminster y en toda el \u00e1rea metropolitana de Denver que han sido <a href=\"\/es\/denver-dog-bite-injury-lawyers\/\">mordido o atacado por perros<\/a>. Kirk McCormick y Jay Murphy comprenden su situaci\u00f3n: atrapado entre sus lesiones f\u00edsicas y la inc\u00f3moda realidad de exigirle responsabilidades a alguien. Nosotros nos encargamos de los aspectos legales para que usted pueda concentrarse en su recuperaci\u00f3n.<\/p><h2><strong>Por qu\u00e9 los casos de mordeduras de perro son diferentes<\/strong><\/h2><p>Los casos de mordeduras de perro se encuentran en una encrucijada inc\u00f3moda. Son reclamaciones por lesiones personales, pero tienen un car\u00e1cter personal que no se percibe en los casos de accidentes de tr\u00e1fico. El perro puede pertenecer a tu vecino. Tus hijos pueden jugar juntos. Puede que hayas acariciado a ese mismo perro docenas de veces antes.<\/p><p>Esta complejidad emocional no altera los hechos. Si un perro le mordi\u00f3 a usted o a su hijo, les caus\u00f3 lesiones y requiri\u00f3 atenci\u00f3n m\u00e9dica, usted tiene derecho a presentar una demanda. La ley de Colorado es clara al respecto.<\/p><p>Lo que hace que estos casos sean particularmente dif\u00edciles es que muchas personas minimizan sus propias lesiones. Un padre cuyo hijo fue mordido puede centrarse \u00fanicamente en la herida f\u00edsica y pasar por alto las pesadillas posteriores. Un adulto que fue atacado mientras corr\u00eda puede restarle importancia a las heridas punzantes porque &quot;podr\u00eda haber sido peor&quot;. Pero la infecci\u00f3n, el da\u00f1o nervioso, las cicatrices y el trauma psicol\u00f3gico son consecuencias muy reales de las mordeduras de perro, y todas ellas influyen en su reclamaci\u00f3n.<\/p><h2><strong>Ley de Colorado sobre mordeduras de perro: lo que necesita saber<\/strong><\/h2><p>Colorado se rige por una ley que responsabiliza estrictamente a los due\u00f1os de perros por ciertas lesiones. Esto significa que si un perro muerde a alguien en un lugar p\u00fablico o legalmente en una propiedad privada, el due\u00f1o es responsable de los da\u00f1os, sin excepci\u00f3n. No es necesario probar la negligencia del due\u00f1o ni que el perro tuviera antecedentes de agresividad.<\/p><p>La ley est\u00e1 dise\u00f1ada de esta manera porque las mordeduras de perro son prevenibles. Se espera que los due\u00f1os controlen a sus animales. Cuando no lo hacen y alguien resulta herido, la ley los responsabiliza.<\/p><p>Sin embargo, existen matices importantes. La ley abarca las mordeduras que causan &quot;lesiones corporales graves&quot;, incluyendo fracturas, desfiguraci\u00f3n y lesiones que requieren m\u00faltiples suturas. Si su lesi\u00f3n no alcanza ese umbral, a\u00fan podr\u00eda tener derecho a presentar una demanda por negligencia seg\u00fan el derecho consuetudinario, pero para ello deber\u00e1 demostrar que el due\u00f1o sab\u00eda o deber\u00eda haber sabido que el perro era peligroso.<\/p><p>Por eso es importante trabajar con un abogado que comprenda estas diferencias. Sabemos c\u00f3mo fundamentar su caso dentro del marco legal aplicable a su situaci\u00f3n particular.<\/p><h2><strong>Lesiones comunes por mordedura de perro en Westminster<\/strong><\/h2><p>Las mordeduras de perro no son heridas simples. Incluso cuando una mordedura parece leve al principio, pueden surgir complicaciones r\u00e1pidamente.<\/p><p>Las heridas punzantes causadas por los dientes de un perro pueden introducir bacterias profundamente en los tejidos, provocando infecciones que requieren hospitalizaci\u00f3n. El da\u00f1o nervioso puede causar p\u00e9rdida permanente de sensibilidad o funci\u00f3n en la mano, el brazo o la pierna. Las mordeduras faciales, especialmente comunes en ni\u00f1os, que suelen estar a la altura de los ojos del perro, pueden dejar cicatrices desfigurantes que requieren cirug\u00eda reconstructiva.<\/p><p>Los perros grandes pueden derribar a sus v\u00edctimas, provoc\u00e1ndoles fracturas, traumatismos craneales y laceraciones por la ca\u00edda. Los adultos mayores y los ni\u00f1os peque\u00f1os son especialmente vulnerables a estas lesiones secundarias.<\/p><p>Luego est\u00e1 el impacto psicol\u00f3gico. Los ni\u00f1os que sufren mordeduras a menudo desarrollan un miedo duradero a los perros. Los adultos pueden experimentar ansiedad, recuerdos intrusivos o conductas de evitaci\u00f3n. Estas no son debilidades, sino respuestas traum\u00e1ticas documentadas. Y son indemnizables seg\u00fan la ley de Colorado.<\/p><h2><strong>Qu\u00e9 hacer despu\u00e9s de una mordedura de perro en Westminster<\/strong><\/h2><p>Los momentos y las horas posteriores a una mordedura de perro son cruciales, tanto para su salud como para cualquier reclamaci\u00f3n legal que pueda interponer.<\/p><p>Primero, busca atenci\u00f3n m\u00e9dica. Aunque la herida parezca leve, las mordeduras de perro conllevan un alto riesgo de infecci\u00f3n. Un m\u00e9dico puede limpiar la herida adecuadamente, evaluar la necesidad de puntos de sutura o antibi\u00f3ticos y documentar la lesi\u00f3n. Ese historial m\u00e9dico ser\u00e1 fundamental para tu reclamaci\u00f3n.<\/p><p>Segundo, identifique al perro y a su due\u00f1o. Obtenga el nombre, la direcci\u00f3n y el n\u00famero de tel\u00e9fono del due\u00f1o. Averig\u00fce si el perro tiene la vacuna antirr\u00e1bica al d\u00eda. Si el servicio de control de animales acude al lugar, obtenga el n\u00famero de informe del incidente.<\/p><p>En tercer lugar, documenta todo. Toma fotos de tus lesiones lo antes posible y repite la experiencia durante los d\u00edas y semanas siguientes, a medida que aparezcan moretones e hinchaz\u00f3n. Anota lo sucedido mientras los detalles est\u00e9n frescos. Si hubo testigos, obt\u00e9n su informaci\u00f3n de contacto.<\/p><p>En cuarto lugar, denuncie la mordedura al Servicio de Control de Animales de Westminster. Esto crea un registro oficial y alerta a las autoridades sobre un perro potencialmente peligroso. Incluso si conoce al due\u00f1o y se siente inc\u00f3modo al hacer la denuncia, este paso protege a otros miembros de su comunidad.<\/p><p>Finalmente, contacte a un abogado especializado en mordeduras de perro antes de hablar con cualquier compa\u00f1\u00eda de seguros. Es probable que el seguro de hogar del propietario cubra su reclamo, pero su ajustador trabaja para ellos, no para usted. Todo lo que diga puede usarse para minimizar su reclamo. Deje que un abogado se encargue de esas conversaciones.<\/p><h2><strong>El papel del seguro de hogar en las reclamaciones por mordeduras de perro<\/strong><\/h2><p>La mayor\u00eda de la gente desconoce que las p\u00f3lizas de seguro de hogar suelen cubrir las mordeduras de perro. Esto es importante porque significa que presentar una reclamaci\u00f3n no implica necesariamente tener que pagarle directamente al vecino. La compa\u00f1\u00eda de seguros cubre los da\u00f1os; para eso se pagan las primas.<\/p><p>Comprender esto puede aliviar parte de la culpa que sienten las personas al presentar una reclamaci\u00f3n. No est\u00e1s arruinando la vida de nadie. Simplemente est\u00e1s exigiendo que la p\u00f3liza de seguro cumpla con lo que est\u00e1 dise\u00f1ada para cubrir.<\/p><p>Dicho esto, las compa\u00f1\u00edas de seguros son empresas. Buscar\u00e1n razones para reducir o denegar su reclamaci\u00f3n. Podr\u00edan argumentar que usted provoc\u00f3 al perro. Podr\u00edan alegar que estaba invadiendo su propiedad. Podr\u00edan ofrecerle un acuerdo r\u00e1pido que parezca razonable, pero que no cubra sus gastos m\u00e9dicos a largo plazo ni tenga en cuenta las cicatrices y el trauma psicol\u00f3gico.<\/p><p>Aqu\u00ed es donde tener a Kirk McCormick o Jay Murphy de su lado marca la diferencia. Sabemos c\u00f3mo operan estas compa\u00f1\u00edas. Sabemos cu\u00e1nto vale realmente su reclamaci\u00f3n. Y no permitimos que los peritos presionen a las personas lesionadas para que acepten menos de lo que les corresponde.<\/p><h2><strong>C\u00f3mo probar su reclamaci\u00f3n por mordedura de perro<\/strong><\/h2><p>Incluso en un estado con responsabilidad objetiva como Colorado, las compa\u00f1\u00edas de seguros examinar\u00e1n minuciosamente su reclamaci\u00f3n. Analizar\u00e1n d\u00f3nde ocurri\u00f3 la mordedura, qu\u00e9 estaba haciendo usted en ese momento y si la lesi\u00f3n cumple con los requisitos legales para ser considerada una &quot;lesi\u00f3n corporal grave&quot;.\u201c<\/p><p>Recopilamos pruebas para su caso, respondiendo a esas preguntas antes de que la compa\u00f1\u00eda de seguros pueda usarlas en su contra. Esto incluye historiales m\u00e9dicos, fotos de sus lesiones, declaraciones de testigos, informes de control animal y documentaci\u00f3n del historial del perro, si corresponde.<\/p><p>Si el perro ya hab\u00eda mordido a alguien, esto refuerza significativamente su reclamaci\u00f3n. Si el due\u00f1o no control\u00f3 al perro o infringi\u00f3 la ley local sobre el uso de la correa, esto respalda el argumento de negligencia. Si la mordedura ocurri\u00f3 en la v\u00eda p\u00fablica o mientras usted se encontraba legalmente en una propiedad privada \u2014entregando un paquete, asistiendo a una fiesta o simplemente caminando por la acera\u2014 la ley est\u00e1 de su lado.<\/p><p>Tambi\u00e9n colaboramos con expertos m\u00e9dicos que pueden dar fe de la gravedad de sus lesiones, el riesgo de complicaciones y la necesidad de tratamiento futuro. En el caso de los ni\u00f1os, podemos consultar con psic\u00f3logos que pueden explicar las consecuencias a largo plazo del trauma.<\/p><h2><strong>Compensaci\u00f3n que usted puede recuperar<\/strong><\/h2><p>Las reclamaciones por mordeduras de perro pueden incluir una indemnizaci\u00f3n por una amplia gama de da\u00f1os. Los gastos m\u00e9dicos son los m\u00e1s evidentes: visitas a urgencias, cirug\u00eda, antibi\u00f3ticos, vacunas contra la rabia y cualquier atenci\u00f3n posterior. Si su hijo necesita una cirug\u00eda de revisi\u00f3n de cicatrices m\u00e1s adelante, esos costos futuros tambi\u00e9n forman parte de su reclamaci\u00f3n.<\/p><p>Tambi\u00e9n puede recuperar los salarios perdidos si sus lesiones le impidieron trabajar. En caso de mordeduras graves que limiten su capacidad para usar la mano o el brazo, esto puede incluir una compensaci\u00f3n por la disminuci\u00f3n de su capacidad para generar ingresos.<\/p><p>Las indemnizaciones por dolor y sufrimiento cubren el dolor f\u00edsico y la angustia emocional que suele seguir a un ataque de perro. En el caso de los ni\u00f1os, esto puede ser considerable. Un ni\u00f1o de siete a\u00f1os que ahora entra en p\u00e1nico al ver perros, se niega a jugar al aire libre y se despierta con pesadillas ha sufrido un da\u00f1o real, y la ley de Colorado lo reconoce.<\/p><p>Si el due\u00f1o del perro actu\u00f3 de forma imprudente \u2014por ejemplo, al dejar suelto a un perro con antecedentes de agresividad en un parque lleno de ni\u00f1os\u2014, usted tambi\u00e9n podr\u00eda tener derecho a una indemnizaci\u00f3n por da\u00f1os punitivos. Estas indemnizaciones tienen como objetivo castigar la conducta reprobable y disuadir a otros de cometer actos similares.<\/p><h2><strong>\u00bfY si el perro perteneciera a alguien que conoces?<\/strong><\/h2><p>Esta es la pregunta que impide que muchas v\u00edctimas de mordeduras de perro busquen ayuda legal. El perro es de tu vecino. Tus hijos van juntos a la escuela. No quieres crear una situaci\u00f3n inc\u00f3moda.<\/p><p>Entendemos esa reticencia. Pero piense en esto: si la situaci\u00f3n fuera al rev\u00e9s, \u00bfno querr\u00eda usted que la persona herida por su perro recibiera la atenci\u00f3n m\u00e9dica que necesita? \u00bfNo esperar\u00eda que su seguro de hogar lo cubriera?<\/p><p>Presentar una reclamaci\u00f3n no se trata de venganza ni de castigo. Se trata de asegurarte de no tener que pagar miles de d\u00f3lares en facturas m\u00e9dicas porque el perro de otra persona te mordi\u00f3. Se trata de garantizar que tu hijo reciba la terapia que necesita para superar su miedo y trauma.<\/p><p>El seguro para due\u00f1os de perros existe precisamente para esta situaci\u00f3n. Usarlo no es una traici\u00f3n. Es sentido com\u00fan.<\/p><p>Y, seg\u00fan nuestra experiencia, la gente lo entiende, sobre todo cuando ven la gravedad de la lesi\u00f3n y los gastos m\u00e9dicos que conlleva. Lo que empieza como una conversaci\u00f3n inc\u00f3moda suele terminar con el due\u00f1o admitiendo que se siente fatal y que quiere asegurarse de que recibas la atenci\u00f3n necesaria.<\/p><h2><strong>\u00bfCu\u00e1nto tiempo tiene para presentar una reclamaci\u00f3n por mordedura de perro en Colorado?<\/strong><\/h2><p>En Colorado, el plazo de prescripci\u00f3n para demandas por lesiones personales, incluidas las mordeduras de perro, suele ser de dos a\u00f1os a partir de la fecha de la lesi\u00f3n. Puede parecer mucho tiempo, pero pasa m\u00e1s r\u00e1pido de lo que uno piensa, sobre todo si se tienen que lidiar con citas m\u00e9dicas, atenci\u00f3n de seguimiento y la realidad diaria de la recuperaci\u00f3n.<\/p><p>M\u00e1s importante a\u00fan, esperar demasiado puede perjudicar su caso. Los testigos olvidan lo que sucede. Los historiales m\u00e9dicos se vuelven m\u00e1s dif\u00edciles de obtener. El perro podr\u00eda morder a otra persona mientras tanto, y el due\u00f1o podr\u00eda tomar medidas para ocultar el historial del animal.<\/p><p>Cuanto antes consulte con un abogado, m\u00e1s s\u00f3lida ser\u00e1 su demanda. En McCormick &amp; Murphy, PC, nos encargamos de reclamaciones por mordeduras de perro en Westminster, Arvada, Thornton, Northglenn y el \u00e1rea metropolitana de Denver. Kirk y Jay conocen bien estos casos y saben lo que se necesita para que nuestros clientes obtengan la indemnizaci\u00f3n que merecen.<\/p><h2><strong>\u00bfPor qu\u00e9 elegir McCormick &amp; Murphy, PC?<\/strong><\/h2><p>Los casos de mordeduras de perro requieren un enfoque legal espec\u00edfico. Se trata de clientes lesionados, a menudo ni\u00f1os, que est\u00e1n asustados y confundidos. Hay que lidiar con p\u00f3lizas de seguro que no se redactaron con claridad. Y, con frecuencia, hay que enfrentarse a peritos que usar\u00e1n cualquier excusa para ofrecer una indemnizaci\u00f3n irrisoria.<\/p><p>Kirk McCormick y Jay Murphy aportan tanto pericia legal como aut\u00e9ntica empat\u00eda a estos casos. No te tratan como un simple n\u00famero de expediente. Te escuchan. Te explican lo que sucede con claridad. Y luchan para garantizar que recibas una compensaci\u00f3n justa, no solo por la lesi\u00f3n visible hoy, sino tambi\u00e9n por las cicatrices, el trauma y el miedo que pueden persistir durante a\u00f1os.<\/p><p>Hemos representado a clientes en Westminster, Wheat Ridge, Lakewood, Commerce City, Aurora, Englewood, Littleton, Centennial y alrededores. Conocemos los tribunales locales, las compa\u00f1\u00edas de seguros que operan en Colorado y las t\u00e1cticas que utilizan para evitar el pago de reclamaciones.<\/p><p>M\u00e1s a\u00fan, sabemos lo que se siente al estar frente a un padre o una madre cuyo hijo tiene miedo de salir de casa, o frente a un adulto que no puede borrar de su mente la imagen de haber sido derribado por un perro. Para nosotros, no son abstracciones. Son la raz\u00f3n por la que hacemos este trabajo.<\/p><h2><strong>Tus derechos no desaparecen por el hecho de que conozcas al due\u00f1o del perro.<\/strong><\/h2><p>Si te ha mordido un perro en Westminster, tienes opciones. Tienes derecho a reclamar una indemnizaci\u00f3n por tus gastos m\u00e9dicos, tu dolor, el trauma sufrido y la p\u00e9rdida de ingresos. Tienes derecho a exigir responsabilidades al due\u00f1o del perro y a su compa\u00f1\u00eda de seguros.<\/p><p>Eso no te convierte en un mal vecino. Te convierte en alguien que se niega a cargar con el peso econ\u00f3mico y emocional de la incapacidad de otra persona para controlar a su animal.<\/p><p>El equipo de McCormick &amp; Murphy, PC est\u00e1 aqu\u00ed para ayudarle a comprender sus derechos y a tomar medidas. Ll\u00e1menos al\u00a0<strong>888-668-1182<\/strong>\u00a0Analizaremos lo sucedido y determinaremos el valor potencial de su caso. Las consultas son gratuitas y solo nos paga si ganamos su caso.<\/p><p>Usted no pidi\u00f3 estar en esta situaci\u00f3n. Pero ahora que est\u00e1 aqu\u00ed, merece un abogado que luche por usted, no solo que se limite a tramitar su caso. Deje que Kirk y Jay se encarguen de los aspectos legales mientras usted se concentra en su recuperaci\u00f3n.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fcd94d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcd94d0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6a760e\" data-id=\"d6a760e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7303432 elementor-widget elementor-widget-heading\" data-id=\"7303432\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Preguntas frecuentes<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3b80d4 elementor-widget elementor-widget-accordion\" data-id=\"d3b80d4\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2221\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2221\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfQu\u00e9 debo hacer inmediatamente despu\u00e9s de una mordedura de perro en Westminster?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2221\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2221\"><p>Busque atenci\u00f3n m\u00e9dica de inmediato, incluso si la herida parece leve. Las mordeduras de perro conllevan un alto riesgo de infecci\u00f3n y complicaciones. Despu\u00e9s de recibir atenci\u00f3n m\u00e9dica, identifique al perro y a su due\u00f1o, documente sus lesiones con fotograf\u00edas, recopile informaci\u00f3n de testigos si alguien presenci\u00f3 el ataque e informe de la mordedura al Control de Animales de Westminster. No hable con la compa\u00f1\u00eda de seguros del due\u00f1o del perro antes de consultar con un abogado. Comun\u00edquese con McCormick &amp; Murphy, PC al 888-668-1182 para obtener asesoramiento sobre c\u00f3mo proteger sus derechos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2222\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2222\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfEs responsable el due\u00f1o del perro aunque este nunca haya mordido a nadie?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2222\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2222\"><p>S\u00ed. La ley de Colorado impone responsabilidad objetiva a los due\u00f1os de perros por mordeduras que causen lesiones corporales graves, independientemente del historial del animal. No es necesario probar que el perro era agresivo antes ni que el due\u00f1o conoc\u00eda una tendencia peligrosa. Si la mordedura caus\u00f3 lesiones significativas, como fracturas, m\u00faltiples suturas o desfiguraci\u00f3n, el due\u00f1o es legalmente responsable. Incluso si la lesi\u00f3n no cumple con el est\u00e1ndar de responsabilidad objetiva, a\u00fan podr\u00eda presentar una demanda por negligencia del due\u00f1o.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2223\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2223\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfCubre el seguro de hogar las lesiones por mordedura de perro en Colorado?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2223\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2223\"><p>La mayor\u00eda de las p\u00f3lizas de seguro de hogar cubren las lesiones por mordedura de perro, lo que significa que su reclamaci\u00f3n generalmente la pagar\u00e1 la aseguradora del due\u00f1o del perro, en lugar de que la abone usted. Esta es una distinci\u00f3n importante que suele tranquilizar a quienes buscan una indemnizaci\u00f3n. Sin embargo, las aseguradoras buscar\u00e1n motivos para reducir o denegar su reclamaci\u00f3n, por lo que es fundamental contar con un abogado con experiencia que gestione las comunicaciones y negociaciones en su nombre.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2224\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2224\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfCu\u00e1nto tiempo tengo para presentar una reclamaci\u00f3n por mordedura de perro en Westminster?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2224\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2224\"><p>En Colorado, el plazo de prescripci\u00f3n para demandas por lesiones personales, incluidas las mordeduras de perro, es generalmente de dos a\u00f1os a partir de la fecha de la lesi\u00f3n. Si bien esto puede parecer tiempo suficiente, la espera puede debilitar su caso, ya que resulta m\u00e1s dif\u00edcil reunir pruebas y los testigos olvidan sus recuerdos. Cuanto antes consulte con un abogado especializado en mordeduras de perro, m\u00e1s s\u00f3lida ser\u00e1 su demanda. Comun\u00edquese con McCormick &amp; Murphy, PC lo antes posible para proteger sus derechos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2225\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2225\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfPuedo presentar una reclamaci\u00f3n si la mordedura del perro ocurri\u00f3 en la propiedad del due\u00f1o?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2225\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2225\"><p>S\u00ed, siempre y cuando usted se encontrara legalmente en la propiedad. La ley de responsabilidad objetiva de Colorado se aplica a las mordeduras que ocurren en propiedad privada si la v\u00edctima ten\u00eda derecho legal a estar all\u00ed, ya sea como invitado, entregando un paquete o por cualquier motivo leg\u00edtimo. Si usted estaba invadiendo propiedad privada, su reclamo se complica, pero a\u00fan podr\u00eda tener opciones bajo la ley de negligencia. Un abogado con experiencia en casos de mordeduras de perro puede evaluar las circunstancias espec\u00edficas de su caso.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2226\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2226\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfY si el perro que me mordi\u00f3 pertenec\u00eda a un amigo o vecino?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2226\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2226\"><p>Muchas personas dudan en presentar una reclamaci\u00f3n cuando conocen personalmente al due\u00f1o del perro, pero buscar una compensaci\u00f3n no significa traicionar a un amigo o vecino. El seguro de hogar existe para cubrir estas situaciones, y presentar una reclamaci\u00f3n simplemente responsabiliza a la compa\u00f1\u00eda de seguros, no a tu amigo. Tus lesiones, gastos m\u00e9dicos y trauma son reales, y no deber\u00edas tener que cargar con la responsabilidad financiera que supone el perro de otra persona. La mayor\u00eda de los due\u00f1os de perros lo entienden una vez que ven la magnitud del da\u00f1o causado.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2227\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2227\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfNecesito demostrar que el due\u00f1o del perro fue negligente en un caso de mordedura de perro en Colorado?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2227\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2227\"><p>Depende de la gravedad de su lesi\u00f3n. En casos de mordeduras que causen lesiones corporales graves, como fracturas, desfiguraci\u00f3n o heridas que requieran m\u00faltiples suturas, se aplica la ley de responsabilidad objetiva de Colorado, y no es necesario probar negligencia. El due\u00f1o es autom\u00e1ticamente responsable. En casos de mordeduras menos graves, es posible que deba probar la negligencia del due\u00f1o demostrando que sab\u00eda o deber\u00eda haber sabido que el perro era peligroso, que no lo sujet\u00f3 o que infringi\u00f3 la ley sobre el uso de correa. Un abogado especializado en mordeduras de perro puede determinar qu\u00e9 marco legal se aplica a su caso.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-2228\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2228\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfQu\u00e9 indemnizaci\u00f3n puedo reclamar tras una lesi\u00f3n por mordedura de perro en Westminster?<\/a>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t<div id=\"elementor-tab-content-2228\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2228\"><p>Usted puede recibir una indemnizaci\u00f3n por gastos m\u00e9dicos, incluyendo atenci\u00f3n de emergencia, cirug\u00eda, medicamentos y tratamientos futuros como la revisi\u00f3n de cicatrices. Tambi\u00e9n tiene derecho a recuperar los salarios perdidos si sus lesiones le impidieron trabajar, as\u00ed como una compensaci\u00f3n por dolor, sufrimiento y angustia emocional. Los ni\u00f1os que desarrollan un miedo duradero a los perros o sufren un trauma pueden recibir una compensaci\u00f3n significativa por da\u00f1os psicol\u00f3gicos. En casos de conducta imprudente por parte del due\u00f1o del perro, tambi\u00e9n pueden aplicarse da\u00f1os punitivos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b45fbd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b45fbd8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c395d74\" data-id=\"c395d74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-577dbb57 elementor-widget elementor-widget-heading\" data-id=\"577dbb57\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfLesionado en un accidente? \u00a1Cont\u00e1ctenos hoy!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b0af151 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1b0af151\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3663b52b elementor-widget elementor-widget-text-editor\" data-id=\"3663b52b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a1Rellena el formulario y nos pondremos en contacto contigo lo antes posible!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44d4dcf elementor-button-align-start elementor-widget elementor-widget-global elementor-global-4170 elementor-widget-form\" data-id=\"44d4dcf\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.19.0 - 05-02-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"11727\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"44d4dcf\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"McCormick &amp; Murphy &#8211; Personal Injury Lawyers\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nombre completo\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_7e89de5 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_7e89de5]\" id=\"form-field-field_7e89de5\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"N\u00famero de tel\u00e9fono\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"S\u00f3lo se aceptan n\u00fameros y caracteres telef\u00f3nicos (#, -, *, etc.).\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-field_776ba71 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[field_776ba71]\" id=\"form-field-field_776ba71\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-field_baef31a elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_baef31a\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tUbicaci\u00f3n\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Colorado Springs\" id=\"form-field-field_baef31a-0\" name=\"form_fields[field_baef31a][]\"> <label for=\"form-field-field_baef31a-0\">Colorado Springs<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Denver\" id=\"form-field-field_baef31a-1\" name=\"form_fields[field_baef31a][]\"> <label for=\"form-field-field_baef31a-1\">Denver<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Pueblo\" id=\"form-field-field_baef31a-2\" name=\"form_fields[field_baef31a][]\"> <label for=\"form-field-field_baef31a-2\">Pueblo<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-field_f44c0f9 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f44c0f9\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u00c1rea de especialidad\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Car Accident\" id=\"form-field-field_f44c0f9-0\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-0\">Accidente de coche<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Motorcycle Accident\" id=\"form-field-field_f44c0f9-1\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-1\">Accidente de motocicleta<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Wrongful Death\" id=\"form-field-field_f44c0f9-2\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-2\">Muerte por negligencia<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Slip &amp; Fall\" id=\"form-field-field_f44c0f9-3\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-3\">Resbal\u00f3n y ca\u00edda<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Insurance Bad Faith\" id=\"form-field-field_f44c0f9-4\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-4\">Mala fe en seguros<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Dog Bite\" id=\"form-field-field_f44c0f9-5\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-5\">Mordedura de perro<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Traumatic Brain Injury\" id=\"form-field-field_f44c0f9-6\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-6\">Lesi\u00f3n cerebral traum\u00e1tica<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Other\" id=\"form-field-field_f44c0f9-7\" name=\"form_fields[field_f44c0f9][]\"> <label for=\"form-field-field_f44c0f9-7\">Otro<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensaje\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_923baa2 elementor-col-100 recaptcha_v3-bottomleft\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_923baa2\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfpixwqAAAAALY-qrx12rHzDvD4l8AL_-lvT7XT\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomleft\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar ahora<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cd45637 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cd45637\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-75bfb91f\" data-id=\"75bfb91f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e6e38d3 elementor-widget elementor-widget-heading\" data-id=\"4e6e38d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Colorado Springs<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b03e91f elementor-widget elementor-widget-text-editor\" data-id=\"2b03e91f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>929 W Colorado Ave,<br \/>Colorado Springs, Colorado<br \/>80905<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2906e2ba elementor-widget elementor-widget-heading\" data-id=\"2906e2ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"e-add-hoverheading elementor-heading-title elementor-size-default\"><a href=\"tel:719-389-0400\">Tel\u00e9fono: (719)-389-0400<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42071306 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"42071306\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/maps.app.goo.gl\/kojCLybzxiurNg5JA\" title=\"Abogados de lesiones personales en Colorado Springs\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtener direcciones<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1cebae7d\" data-id=\"1cebae7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-519dc941 elementor-widget elementor-widget-heading\" data-id=\"519dc941\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pueblo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d617992 elementor-widget elementor-widget-text-editor\" data-id=\"1d617992\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>301 N. Calle principal,<br \/>Pueblo, Colorado<br \/>81003<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ada7dfd elementor-widget elementor-widget-heading\" data-id=\"7ada7dfd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"e-add-hoverheading elementor-heading-title elementor-size-default\"><a href=\"tel:(888)-668-1182\">Tel\u00e9fono: (888)-668-1182<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27c1a0f6 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"27c1a0f6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/maps.app.goo.gl\/eirbTTn8gtvYxwm98\" title=\"Abogados de lesiones personales en Pueblo\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtener direcciones<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-206a66c4\" data-id=\"206a66c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-198b22e7 elementor-widget elementor-widget-heading\" data-id=\"198b22e7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Denver<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57637af6 elementor-widget elementor-widget-text-editor\" data-id=\"57637af6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"text_block-107-192\" class=\"ct-text-block\">1547 N. Gaylord St.,<br \/>Unidad 303<br \/>Denver, Colorado 80206<\/div><div id=\"div_block-98-192\" class=\"ct-div-block\"><div id=\"text_block-99-192\" class=\"ct-text-block phone-cont\">\u00a0<\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-106eddcc elementor-widget elementor-widget-heading\" data-id=\"106eddcc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"e-add-hoverheading elementor-heading-title elementor-size-default\"><a href=\"tel:(888)-668-1182\">Tel\u00e9fono: (888)-668-1182<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dbdbfa6 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"1dbdbfa6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/maps.app.goo.gl\/y9gVVznr14hyoWwr9\" title=\"Abogados de lesiones personales en Denver\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtener direcciones<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f158b3e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f158b3e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-376f6465\" data-id=\"376f6465\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-34df6e5b\" data-id=\"34df6e5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14326b06 elementor-widget elementor-widget-image\" data-id=\"14326b06\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"372\" height=\"113\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/09\/mccormick-logo-new.png\" class=\"attachment-large size-large wp-image-975\" alt=\"\" srcset=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/09\/mccormick-logo-new.png 372w, https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/09\/mccormick-logo-new-300x91.png 300w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e6f3c14\" data-id=\"e6f3c14\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eb757dc elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eb757dc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-e-bg-lazyload=\"\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2cf2460\" data-id=\"2cf2460\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-38df2d90\" data-id=\"38df2d90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c7dfba7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7dfba7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-45435a85\" data-id=\"45435a85\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e553e22 elementor-widget elementor-widget-image\" data-id=\"2e553e22\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"49\" height=\"49\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2024\/02\/twitter-gold.png\" class=\"attachment-large size-large wp-image-2571\" alt=\"\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-254412d\" data-id=\"254412d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f0fdd1b elementor-widget elementor-widget-image\" data-id=\"2f0fdd1b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/McCormickMurphy\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"49\" height=\"49\" src=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2024\/02\/fb-gold.png\" class=\"attachment-large size-large wp-image-2572\" alt=\"\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3557e7da\" data-id=\"3557e7da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-358d4458 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"358d4458\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78a5b04a\" data-id=\"78a5b04a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16f02e34 elementor-widget elementor-widget-heading\" data-id=\"16f02e34\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Opina sobre nosotros en Google<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34ff68ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34ff68ac\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-25598db0\" data-id=\"25598db0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-628fa815 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"628fa815\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.google.com\/search?q=McCormick+%26+Murphy%2C+P.C.+Colorado+Springs&#038;sca_esv=582393838&#038;rlz=1C1CHBD_enUS941US943&#038;ei=m-tTZZn7AcmoqtsP7rmt8Ao&#038;ved=0ahUKEwjZtLmuvMSCAxVJlGoFHe5cC64Q4dUDCBA&#038;uact=5&#038;oq=McCormick+%26+Murphy%2C+P.C.+Colorado+Springs&#038;gs_lp=Egxnd3Mtd2l6LXNlcnAiKU1jQ29ybWljayAmIE11cnBoeSwgUC5DLiBDb2xvcmFkbyBTcHJpbmdzMgUQABiiBDIFEAAYogQyBRAAGKIESLIhUO4GWN0fcAJ4AJABAJgBrgGgAaQMqgEEMTMuM7gBA8gBAPgBAcICAhAm4gMEGAEgQYgGAQ&#038;sclient=gws-wiz-serp#lrd=0x8713453243ee88c7:0x89c7f2c6c084c442,1,,,,\" title=\"Rese\u00f1a de abogados de lesiones personales de Colorado Springs\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Colorado Springs<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-36b0459\" data-id=\"36b0459\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26eb6bc1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"26eb6bc1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.google.com\/search?q=McCormick+%26+Murphy%2C+P.C.+Pueblo&#038;sca_esv=582393838&#038;rlz=1C1CHBD_enUS941US943&#038;ei=4-tTZfrTN4ncqtsPxLaHYA&#038;ved=0ahUKEwi60ZnRvMSCAxUJrmoFHUTbAQwQ4dUDCBA&#038;uact=5&#038;oq=McCormick+%26+Murphy%2C+P.C.+Pueblo&#038;gs_lp=Egxnd3Mtd2l6LXNlcnAiH01jQ29ybWljayAmIE11cnBoeSwgUC5DLiBQdWVibG8yBRAhGKABMgUQIRigAUjCJFC0FFjmH3ADeAGQAQCYAYMBoAHOBKoBAzQuMrgBA8gBAPgBAcICChAAGEcY1gQYsAPCAgIQJuIDBBgAIEGIBgGQBgI&#038;sclient=gws-wiz-serp#lrd=0x8713a303b247ef69:0x94b2cd814dfabe26,1,,,,\" title=\"Rese\u00f1a de los abogados de lesiones personales de Pueblo\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Pueblo<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-282f7c35\" data-id=\"282f7c35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c450e1f elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"3c450e1f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.google.com\/search?q=McCormick+%26+Murphy%2C+P.C.+Denver&#038;sca_esv=582393838&#038;rlz=1C1CHBD_enUS941US943&#038;ei=-utTZb79GZCpqtsPt7-JmAY&#038;ved=0ahUKEwi-4vfbvMSCAxWQlGoFHbdfAmMQ4dUDCBA&#038;uact=5&#038;oq=McCormick+%26+Murphy%2C+P.C.+Denver&#038;gs_lp=Egxnd3Mtd2l6LXNlcnAiH01jQ29ybWljayAmIE11cnBoeSwgUC5DLiBEZW52ZXIyAhAmSPYNUIwHWKgMcAJ4AJABAJgBVaABzQOqAQE2uAEDyAEA-AEBwgIIEAAYogQYsAPiAwQYASBBiAYBkAYC&#038;sclient=gws-wiz-serp#lrd=0x876c7eb5457a815b:0x993bb4fecef454ff,1,,,,\" title=\"Rese\u00f1a de abogados especializados en lesiones personales en Denver\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Denver<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53dc1c34 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53dc1c34\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1815f46\" data-id=\"1815f46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a874abf elementor-widget elementor-widget-text-editor\" data-id=\"4a874abf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Descargo de responsabilidad: La informaci\u00f3n que se incluye en este sitio web es solo para fines informativos. Este sitio web no debe tomarse como asesoramiento legal. Los resultados anteriores no garantizan un resultado similar. Esta informaci\u00f3n no debe tomarse como la formaci\u00f3n de una relaci\u00f3n abogado-cliente.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61498143 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"61498143\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a86cf9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a86cf9b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68ee5420\" data-id=\"68ee5420\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e674cd4 elementor-widget elementor-widget-text-editor\" data-id=\"7e674cd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a9\u00a0<span id=\"span-97-46\" class=\"ct-span\">2026<\/span>\u00a0McCormick &amp; Murphy, PC | Todos los derechos reservados |\u00a0<a href=\"https:\/\/mccormickmurphy.com\/es\/privacy-policy\/\">pol\u00edtica de privacidad<\/a>\u00a0|\u00a0<a href=\"https:\/\/mccormickmurphy.com\/es\/terms-and-conditions\/\">T\u00e9rminos y condiciones<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Colorado Springs Pueblo Denver Call (888)-668-1182 Dog Bite Lawyer Westminster A dog bite changes everything in an instant. One moment you&#8217;re walking your own dog, greeting a neighbor, or watching your child play outside. The next, you&#8217;re bleeding, in pain, and trying to make sense of what just happened. If the dog belongs to someone &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/mccormickmurphy.com\/es\/westminster-dog-bite-lawyer\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Dog Bite Lawyer Westminster&#8221;<\/span><\/a><\/p>","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-11727","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dog Bite Lawyer Westminster - McCormick &amp; Murphy - Personal Injury Lawyers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mccormickmurphy.com\/es\/westminster-dog-bite-lawyer\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dog Bite Lawyer Westminster\" \/>\n<meta property=\"og:description\" content=\"Colorado Springs Pueblo Denver Call (888)-668-1182 Dog Bite Lawyer Westminster A dog bite changes everything in an instant. One moment you&#8217;re walking your own dog, greeting a neighbor, or watching your child play outside. The next, you&#8217;re bleeding, in pain, and trying to make sense of what just happened. If the dog belongs to someone &hellip; Continuar leyendo &quot;Dog Bite Lawyer Westminster&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mccormickmurphy.com\/es\/westminster-dog-bite-lawyer\/\" \/>\n<meta property=\"og:site_name\" content=\"McCormick &amp; Murphy - Personal Injury Lawyers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T16:40:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/\",\"url\":\"https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/\",\"name\":\"Dog Bite Lawyer Westminster - McCormick &amp; Murphy - Personal Injury Lawyers\",\"isPartOf\":{\"@id\":\"https:\/\/mccormickmurphy.com\/#website\"},\"datePublished\":\"2026-05-14T14:40:52+00:00\",\"dateModified\":\"2026-06-22T16:40:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mccormickmurphy.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dog Bite Lawyer Westminster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mccormickmurphy.com\/#website\",\"url\":\"https:\/\/mccormickmurphy.com\/\",\"name\":\"McCormick &amp; Murphy - Personal Injury Lawyers\",\"description\":\"Premier Colorado Personal Injury Lawyers\",\"publisher\":{\"@id\":\"https:\/\/mccormickmurphy.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mccormickmurphy.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mccormickmurphy.com\/#organization\",\"name\":\"McCormick & Murphy, P.C.\",\"url\":\"https:\/\/mccormickmurphy.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mccormickmurphy.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png\",\"contentUrl\":\"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png\",\"width\":261,\"height\":80,\"caption\":\"McCormick & Murphy, P.C.\"},\"image\":{\"@id\":\"https:\/\/mccormickmurphy.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dog Bite Lawyer Westminster - McCormick &amp; Murphy - Personal Injury Lawyers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mccormickmurphy.com\/es\/westminster-dog-bite-lawyer\/","og_locale":"es_MX","og_type":"article","og_title":"Dog Bite Lawyer Westminster","og_description":"Colorado Springs Pueblo Denver Call (888)-668-1182 Dog Bite Lawyer Westminster A dog bite changes everything in an instant. One moment you&#8217;re walking your own dog, greeting a neighbor, or watching your child play outside. The next, you&#8217;re bleeding, in pain, and trying to make sense of what just happened. If the dog belongs to someone &hellip; Continuar leyendo \"Dog Bite Lawyer Westminster\"","og_url":"https:\/\/mccormickmurphy.com\/es\/westminster-dog-bite-lawyer\/","og_site_name":"McCormick &amp; Murphy - Personal Injury Lawyers","article_modified_time":"2026-06-22T16:40:52+00:00","og_image":[{"url":"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/","url":"https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/","name":"Dog Bite Lawyer Westminster - McCormick &amp; Murphy - Personal Injury Lawyers","isPartOf":{"@id":"https:\/\/mccormickmurphy.com\/#website"},"datePublished":"2026-05-14T14:40:52+00:00","dateModified":"2026-06-22T16:40:52+00:00","breadcrumb":{"@id":"https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mccormickmurphy.com\/westminster-dog-bite-lawyer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mccormickmurphy.com\/"},{"@type":"ListItem","position":2,"name":"Dog Bite Lawyer Westminster"}]},{"@type":"WebSite","@id":"https:\/\/mccormickmurphy.com\/#website","url":"https:\/\/mccormickmurphy.com\/","name":"McCormick &amp; Murphy - Abogados de lesiones personales","description":"Abogados de lesiones personales de primer nivel en Colorado","publisher":{"@id":"https:\/\/mccormickmurphy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mccormickmurphy.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mccormickmurphy.com\/#organization","name":"McCormick y Murphy, PC","url":"https:\/\/mccormickmurphy.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mccormickmurphy.com\/#\/schema\/logo\/image\/","url":"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png","contentUrl":"https:\/\/mccormickmurphy.com\/wp-content\/uploads\/2023\/07\/header-logo.png","width":261,"height":80,"caption":"McCormick & Murphy, P.C."},"image":{"@id":"https:\/\/mccormickmurphy.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/comments?post=11727"}],"version-history":[{"count":7,"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11727\/revisions"}],"predecessor-version":[{"id":12591,"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/pages\/11727\/revisions\/12591"}],"wp:attachment":[{"href":"https:\/\/mccormickmurphy.com\/es\/wp-json\/wp\/v2\/media?parent=11727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}